{"id":5119,"date":"2020-12-11T08:47:02","date_gmt":"2020-12-11T01:47:02","guid":{"rendered":"http:\/\/krukob.com\/web\/?page_id=5119"},"modified":"2020-12-15T09:23:20","modified_gmt":"2020-12-15T02:23:20","slug":"work","status":"publish","type":"page","link":"https:\/\/krukob.com\/web\/work\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563"},"content":{"rendered":"<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:25%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5120\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-1-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg?fit=709%2C1024&amp;ssl=1\" data-attachment-id=\"5120\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-1-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg?fit=709%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 1 of 6 in full-screen\"srcset=\"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg?strip=info&#038;w=600 600w,https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg?strip=info&#038;w=720 720w\" alt=\"\" data-height=\"1040\" data-id=\"5120\" data-link=\"http:\/\/krukob.com\/web\/work\/slide1-1-3\/\" data-url=\"http:\/\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg\" data-width=\"720\" src=\"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-1.jpeg\" layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5125\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-12\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg?fit=709%2C1024&amp;ssl=1\" data-attachment-id=\"5125\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-12\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg?fit=709%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 2 of 6 in full-screen\"srcset=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg?strip=info&#038;w=720 720w\" alt=\"\" data-height=\"1040\" data-id=\"5125\" data-link=\"http:\/\/krukob.com\/web\/work\/slide1-12\/\" data-url=\"http:\/\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg\" data-width=\"720\" src=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-5.jpeg\" layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5121\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-8\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg?fit=709%2C1024&amp;ssl=1\" data-attachment-id=\"5121\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-8\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg?fit=709%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 3 of 6 in full-screen\"srcset=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg?strip=info&#038;w=720 720w\" alt=\"\" data-height=\"1040\" data-id=\"5121\" data-link=\"http:\/\/krukob.com\/web\/work\/slide1-8\/\" data-url=\"http:\/\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg\" data-width=\"720\" src=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-2.jpeg\" layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:25%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5122\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-9\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg?fit=709%2C1024&amp;ssl=1\" data-attachment-id=\"5122\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-9\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg?fit=709%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 4 of 6 in full-screen\"srcset=\"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg?strip=info&#038;w=600 600w,https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg?strip=info&#038;w=720 720w\" alt=\"\" data-height=\"1040\" data-id=\"5122\" data-link=\"http:\/\/krukob.com\/web\/work\/slide1-9\/\" data-url=\"http:\/\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg\" data-width=\"720\" src=\"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-3.jpeg\" layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5123\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-10\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg?fit=709%2C1024&amp;ssl=1\" data-attachment-id=\"5123\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-10\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg?fit=709%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 5 of 6 in full-screen\"srcset=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg?strip=info&#038;w=720 720w\" alt=\"\" data-height=\"1040\" data-id=\"5123\" data-link=\"http:\/\/krukob.com\/web\/work\/slide1-10\/\" data-url=\"http:\/\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg\" data-width=\"720\" src=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-4.jpeg\" layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"5322\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-13\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg?fit=709%2C1024&amp;ssl=1\" data-attachment-id=\"5322\" data-permalink=\"https:\/\/krukob.com\/web\/work\/slide1-13\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg?fit=720%2C1040&amp;ssl=1\" data-orig-size=\"720,1040\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Slide1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg?fit=709%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 6 of 6 in full-screen\"srcset=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg?strip=info&#038;w=600 600w,https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg?strip=info&#038;w=720 720w\" alt=\"\" data-height=\"1040\" data-id=\"5322\" data-link=\"http:\/\/krukob.com\/web\/work\/slide1-13\/\" data-url=\"http:\/\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg\" data-width=\"720\" src=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1-6.jpeg\" layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div>\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563<\/p>\n","protected":false},"author":1,"featured_media":5126,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"class_list":["post-5119","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563 &#187; Digital Learning Classroom<\/title>\n<meta name=\"description\" content=\"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/krukob.com\/web\/work\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563 &#187; Digital Learning Classroom\" \/>\n<meta property=\"og:description\" content=\"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/krukob.com\/web\/work\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Learning Classroom\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-15T02:23:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"362\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@musicmankob\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/\",\"name\":\"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563 &#187; Digital Learning Classroom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1\",\"datePublished\":\"2020-12-11T01:47:02+00:00\",\"dateModified\":\"2020-12-15T02:23:20+00:00\",\"description\":\"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1\",\"width\":1024,\"height\":362},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/krukob.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/\",\"name\":\"Digital Learning Classroom\",\"description\":\"Digital Learning Classroom\",\"publisher\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/krukob.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\",\"name\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"width\":500,\"height\":500,\"caption\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\"},\"logo\":{\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563 &#187; Digital Learning Classroom","description":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/krukob.com\/web\/work\/","og_locale":"en_US","og_type":"article","og_title":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563 &#187; Digital Learning Classroom","og_description":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19","og_url":"https:\/\/krukob.com\/web\/work\/","og_site_name":"Digital Learning Classroom","article_modified_time":"2020-12-15T02:23:20+00:00","og_image":[{"width":1024,"height":362,"url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@musicmankob","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/krukob.com\/web\/work\/","url":"https:\/\/krukob.com\/web\/work\/","name":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563 &#187; Digital Learning Classroom","isPartOf":{"@id":"https:\/\/krukob.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/krukob.com\/web\/work\/#primaryimage"},"image":{"@id":"https:\/\/krukob.com\/web\/work\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1","datePublished":"2020-12-11T01:47:02+00:00","dateModified":"2020-12-15T02:23:20+00:00","description":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19","breadcrumb":{"@id":"https:\/\/krukob.com\/web\/work\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/krukob.com\/web\/work\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/krukob.com\/web\/work\/#primaryimage","url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1","contentUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/2020-12-11_08-55-22.jpg?fit=1024%2C362&ssl=1","width":1024,"height":362},{"@type":"BreadcrumbList","@id":"https:\/\/krukob.com\/web\/work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/krukob.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563"}]},{"@type":"WebSite","@id":"https:\/\/krukob.com\/web\/#website","url":"https:\/\/krukob.com\/web\/","name":"Digital Learning Classroom","description":"Digital Learning Classroom","publisher":{"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/krukob.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6","name":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","url":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","contentUrl":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","width":500,"height":500,"caption":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14"},"logo":{"@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500"}}]}},"jetpack_shortlink":"https:\/\/wp.me\/P8LKk5-1kz","jetpack-related-posts":[{"id":5112,"url":"https:\/\/krukob.com\/web\/%e0%b8%9c%e0%b8%a5%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9b%e0%b8%8f%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b5%e0%b9%88\/","url_meta":{"origin":5119,"position":0},"title":"\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"December 9, 2020","format":false,"excerpt":"\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/12\/Slide1.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":674,"url":"https:\/\/krukob.com\/web\/%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%9a%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%aa%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b8%82%e0%b9%88%e0%b8%b2\/","url_meta":{"origin":5119,"position":1},"title":"\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e21.5","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"May 30, 2017","format":false,"excerpt":"\u0e04\u0e33\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\/\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e2b\u0e31\u0e2a\u0e27\u0e34\u0e0a\u0e32 \u0e0731201\u00a0 \u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48 5 \u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48 1 \u0e40\u0e27\u0e25\u0e32 80 \u0e04\u0e32\u0e1a\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e08\u0e33\u0e19\u0e27\u0e19 2 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e04\u0e33\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 ( course description ) \u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e42\u0e15\u0e04\u0e2d\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e42\u0e2d\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e1a\u0e1a\u0e02\u0e19\u0e32\u0e19\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e2d\u0e19\u0e38\u0e01\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e42\u0e15\u0e04\u0e2d\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e01\u0e34\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e38\u0e20\u0e32\u0e1e \u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e02\u0e49\u0e2d\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e21\u0e35\u0e28\u0e35\u0e25\u0e18\u0e23\u0e23\u0e21 \u0e21\u0e35\u0e08\u0e34\u0e15\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e41\u0e25\u0e30\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u00a0 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e39\u0e49\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23 \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32(\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19)\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e07 3.1 \u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e40\u0e2b\u0e47\u0e19\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e1a\u0e04\u0e49\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":68,"url":"https:\/\/krukob.com\/web\/%e0%b9%83%e0%b8%84%e0%b8%a3%e0%b8%84%e0%b8%a3%e0%b8%b9%e0%b8%81%e0%b8%9a\/","url_meta":{"origin":5119,"position":2},"title":"\u0e04\u0e23\u0e39\u0e01\u0e1a\u0e04\u0e37\u0e2d\u0e43\u0e04\u0e23?","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"April 14, 2017","format":false,"excerpt":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 Ph.D. (Doctor of Philosophy) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c (Kasetsart University) \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (Educational Communications and Technology) \u0e1b\u0e35\u00a02558 \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1d\u0e36\u0e01\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e University of Northern Colorado (UNC) \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e1b\u0e35 2556 \u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e42\u0e17 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e28\u0e29.\u0e21. (Master of Education: M.Ed.) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 (Ramkhamhaeng University) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (Educational Administration) \u0e1b\u0e35 2553 \u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e42\u0e17 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e28\u0e29.\u0e21. (Master\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2024\/06\/IMG_9090.jpg?fit=472%2C626&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":81,"url":"https:\/\/krukob.com\/web\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%aa%e0%b9%88%e0%b8%a7%e0%b8%99%e0%b8%95%e0%b8%b1%e0%b8%a7\/","url_meta":{"origin":5119,"position":3},"title":"\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"April 14, 2017","format":false,"excerpt":"\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e40\u0e2d\u0e01 \u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 Ph.D. (Doctor of Philosophy) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c (Kasetsart University) \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (Educational Communications and Technology) \u0e1b\u0e35\u00a02558 \u0e19\u0e34\u0e2a\u0e34\u0e15\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1d\u0e36\u0e01\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e University of Northern Colorado (UNC) \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e2b\u0e23\u0e31\u0e10\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e1b\u0e35 2556 \u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e42\u0e17 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e28\u0e29.\u0e21. (Master of Education: M.Ed.) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 (Ramkhamhaeng University) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (Educational Administration) \u0e1b\u0e35 2553 \u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e42\u0e17 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e28\u0e29.\u0e21. (Master of Education: M.Ed.) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450,"url":"https:\/\/krukob.com\/web\/1-2\/","url_meta":{"origin":5119,"position":4},"title":"\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"May 18, 2018","format":false,"excerpt":"\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\/\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e21\u0e47\u0e04\u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e01\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e39\u0e48\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u00a0 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e42\u0e21\u0e1a\u0e32\u0e22 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (PLC) \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e 2. \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e43\u0e19\u0e28\u0e15\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 21 (3Rs8Cs) \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e22\u0e38\u0e04 Thailand 4.0 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b Speexx \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 (Basic User A1-A2) 5. \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b Speexx \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e25\u0e32\u0e07 (Independent User B1-B2) \u00a0","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6422,"url":"https:\/\/krukob.com\/web\/profile\/","url_meta":{"origin":5119,"position":5},"title":"\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"April 1, 2021","format":false,"excerpt":"\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23 \u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002817.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002817.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002817.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002817.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002817.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/pages\/5119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/comments?post=5119"}],"version-history":[{"count":2,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/pages\/5119\/revisions"}],"predecessor-version":[{"id":5327,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/pages\/5119\/revisions\/5327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media\/5126"}],"wp:attachment":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media?parent=5119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}