{"id":15683,"date":"2025-11-13T18:59:38","date_gmt":"2025-11-13T11:59:38","guid":{"rendered":"https:\/\/krukob.com\/web\/?p=15683"},"modified":"2025-11-14T14:33:54","modified_gmt":"2025-11-14T07:33:54","slug":"sv-48","status":"publish","type":"post","link":"https:\/\/krukob.com\/web\/sv-48\/","title":{"rendered":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&#8221; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22"},"content":{"rendered":"<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>\n<h1 class=\"wp-block-heading\"><strong><br>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&#8221; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22<\/strong><\/h1>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14<br>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e2a\u0e1e\u0e21.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32<br><a href=\"mailto:Musicmankob@gmail.com\">Musicmankob@gmail.com<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><br>__________________________________<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 1: \u0e1a\u0e17\u0e19\u0e33 &#8211; \u0e27\u0e34\u0e01\u0e24\u0e15\u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e33\u0e16\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e2d\u0e07 &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c&#8221;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32 \u201c\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21\u201d \u0e16\u0e39\u0e01\u0e2b\u0e22\u0e34\u0e1a\u0e22\u0e01\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e43\u0e19\u0e41\u0e27\u0e14\u0e27\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e04\u0e33\u0e16\u0e32\u0e21\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49 \u0e41\u0e15\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49 <sup>1<\/sup> \u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e2d\u0e38\u0e14\u0e21\u0e04\u0e15\u0e34 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c (Educational Supervisor) \u0e16\u0e39\u0e01\u0e27\u0e32\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e44\u0e27\u0e49\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30 &#8220;\u0e2a\u0e16\u0e32\u0e1b\u0e19\u0e34\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&#8221; (Learning Architect) \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u201d (Academic Leader) <sup>2<\/sup> \u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e43\u0e19\u0e42\u0e25\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e31\u0e01\u0e16\u0e39\u0e01\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e1a \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30 \u201c\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u201d (Inspector) \u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e1c\u0e34\u0e14, \u201c\u0e40\u0e08\u0e49\u0e32\u0e19\u0e32\u0e22\u201d (Boss) \u0e17\u0e35\u0e48\u0e21\u0e32\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e15\u0e32\u0e2a\u0e39\u0e07 <sup>1<\/sup>, \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07 \u201c\u0e1c\u0e39\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u201d \u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07 <sup>4<\/sup> \u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e16\u0e39\u0e01\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19 <sup>4<\/sup> \u0e44\u0e14\u0e49\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 \u201c\u0e27\u0e34\u0e01\u0e24\u0e15\u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u201d (Identity Crisis) \u0e02\u0e2d\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e21\u0e38\u0e48\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01 (The &#8216;Why&#8217;) \u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e15\u0e32\u0e21\u0e01\u0e23\u0e2d\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/li>\n\n\n\n<li>\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 (The &#8216;How&#8217;) \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48<\/li>\n\n\n\n<li>\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21 (Case Studies) \u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34<\/li>\n\n\n\n<li>\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 (Perspectives) \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e25\u0e31\u0e01 (\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23)<\/li>\n\n\n\n<li>\u0e0a\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 (Challenges) \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b (Reforms) \u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e02\u0e49\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c &#8220;\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07&#8221; (The Gap) \u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 &#8220;\u0e17\u0e24\u0e29\u0e0e\u0e35&#8221; (\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e04\u0e27\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19) \u0e41\u0e25\u0e30 &#8220;\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34&#8221; (\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49) \u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e38\u0e1b\u0e43\u0e19\u0e15\u0e32\u0e23\u0e32\u0e07\u0e17\u0e35\u0e48 1 \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e2a\u0e14\u0e07\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e30\u0e17\u0e30\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e15\u0e32\u0e23\u0e32\u0e07\u0e17\u0e35\u0e48 1: \u0e01\u0e32\u0e23\u0e1b\u0e30\u0e17\u0e30\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c (Paradigm Clash) \u0e43\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>\u0e21\u0e34\u0e15\u0e34\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28<\/strong><\/td><td><strong>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e40\u0e14\u0e34\u0e21 (Inspector\/Auditor)<\/strong><\/td><td><strong>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 (Partner\/Coach)<\/strong><\/td><\/tr><tr><td><strong>\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01<\/strong><\/td><td>\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e40\u0e01\u0e13\u0e11\u0e4c (Compliance) <sup>5<\/sup><\/td><td>\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 (Capacity-Building) <sup>5<\/sup><\/td><\/tr><tr><td><strong>\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/strong><\/td><td>\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08 vs. \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08, \u0e1c\u0e39\u0e49\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23 <sup>1<\/sup><\/td><td>\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23, \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14, \u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 <sup>2<\/sup><\/td><\/tr><tr><td><strong>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01<\/strong><\/td><td>\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a (Checklist), \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 <sup>5<\/sup><\/td><td>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a (Coaching), PLC <sup>5<\/sup><\/td><\/tr><tr><td><strong>\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/strong><\/td><td>\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08, \u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 <sup>4<\/sup><\/td><td>\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19, \u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19 <sup>10<\/sup><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 2: \u0e41\u0e01\u0e48\u0e19\u0e41\u0e17\u0e49\u0e41\u0e25\u0e30\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08 &#8211; \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c &#8220;\u0e04\u0e37\u0e2d\u0e43\u0e04\u0e23&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23&#8221; \u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e27\u0e48\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e01\u0e23\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e20\u0e32\u0e23\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2.1 \u0e01\u0e32\u0e23\u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 (\u0e273\/2564)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c (\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01.\u0e04.\u0e28. \u0e17\u0e35\u0e48 \u0e28\u0e18 0206.4\/\u0e27 3 \u0e25\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2564) <sup>12<\/sup> \u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e44\u0e27\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e01 3 \u0e14\u0e49\u0e32\u0e19 <sup>2<\/sup> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32:<\/strong> \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 <sup>14<\/sup><\/li>\n\n\n\n<li><strong>\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32:<\/strong> \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 <sup>15<\/sup><\/li>\n\n\n\n<li><strong>\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e:<\/strong> \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e2d\u0e1a\u0e23\u0e39\u0e49 \u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (\u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e27\u0e34\u0e08\u0e31\u0e22 R&amp;D) <sup>2<\/sup><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e22\u0e31\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e2d\u0e07 &#8220;\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32&#8221; \u0e43\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e23\u0e2d\u0e1a\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 7-8 \u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23, \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25, \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e, \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e37\u0e48\u0e2d, \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e40\u0e25\u0e02\u0e32\u0e19\u0e38\u0e01\u0e32\u0e23\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 \u0e01.\u0e15.\u0e1b.\u0e19. <sup>16<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2.2 \u0e04\u0e27\u0e32\u0e21\u0e02\u0e31\u0e14\u0e41\u0e22\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1d\u0e31\u0e07\u0e25\u0e36\u0e01\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19 (The Built-in Role Conflict)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01 <sup>15<\/sup> \u0e40\u0e1c\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e21\u0e31\u0e01\u0e16\u0e39\u0e01\u0e21\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e21 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d \u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07 &#8220;\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28&#8221; \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 <strong>\u201c\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u201d<\/strong> \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 <sup>15<\/sup> \u0e41\u0e25\u0e30 &#8220;\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23&#8221; <sup>17<\/sup> \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d &#8220;\u0e04\u0e27\u0e32\u0e21\u0e02\u0e31\u0e14\u0e41\u0e22\u0e49\u0e07\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07&#8221; (Structural Conflict) \u0e17\u0e35\u0e48\u0e1d\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e04\u0e33\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e07\u0e32\u0e19 (Job Description) \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e16\u0e39\u0e01\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e04\u0e23\u0e39\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23&#8221; (Academic Leader) <sup>16<\/sup> \u0e41\u0e15\u0e48\u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e01\u0e47\u0e16\u0e39\u0e01\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23&#8221; \u0e02\u0e2d\u0e07\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 <sup>15<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35 &#8220;\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e21\u0e32\u0e41\u0e17\u0e23\u0e01&#8221; \u0e08\u0e19 &#8220;\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e34\u0e49\u0e07\u0e07\u0e32\u0e19\u0e19\u0e34\u0e40\u0e17\u0e28\u0e44\u0e1b&#8221; <sup>18<\/sup> \u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e2d\u0e38\u0e14\u0e21\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e02\u0e31\u0e14\u0e41\u0e22\u0e49\u0e07\u0e43\u0e19\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e35\u0e48\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48 &#8220;\u0e27\u0e34\u0e01\u0e24\u0e15\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d&#8221; (Credibility Crisis) <sup>4<\/sup> \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23 (\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19) \u0e16\u0e39\u0e01\u0e40\u0e1a\u0e35\u0e48\u0e22\u0e07\u0e40\u0e1a\u0e19\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2.3 \u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e17\u0e1a\u0e32\u0e17: \u0e08\u0e32\u0e01 &#8220;\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e01\u0e32\u0e23&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32&#8221;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e15\u0e32\u0e21\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e22\u0e38\u0e04\u0e2a\u0e21\u0e31\u0e22 \u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15 \u0e04\u0e33\u0e27\u0e48\u0e32 &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c&#8221; (Supervisor) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e43\u0e0a\u0e49\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e43\u0e19\u0e44\u0e17\u0e22\u0e23\u0e32\u0e27\u0e1b\u0e35 \u0e1e.\u0e28. 2495 <sup>19<\/sup> \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 &#8220;\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e15\u0e23\u0e32&#8221; (Inspector) <sup>20<\/sup> \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 (Compliance) <sup>5<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e43\u0e19\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e15\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 21 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c (Paradigm Shift) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d <sup>5<\/sup> \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e08\u0e32\u0e01 (From):<\/strong> &#8220;\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25&#8221; (Inspector\/Evaluator)<\/li>\n\n\n\n<li><strong>\u0e2a\u0e39\u0e48 (To):<\/strong> &#8220;\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32&#8221; (Developmental Partner) \u0e41\u0e25\u0e30 &#8220;\u0e42\u0e04\u0e49\u0e0a&#8221; (Coach)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23 &#8220;\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e40\u0e01\u0e13\u0e11\u0e4c&#8221; \u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23 &#8220;\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16&#8221; (Capacity-Building) \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 <sup>5<\/sup> \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e30\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19&#8221; \u0e41\u0e25\u0e49\u0e27 <sup>6<\/sup> \u0e41\u0e15\u0e48\u0e20\u0e32\u0e1e\u0e08\u0e33\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15 <sup>20<\/sup> \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e22\u0e36\u0e14\u0e15\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e42\u0e21\u0e40\u0e14\u0e25 &#8220;\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e01\u0e32\u0e23&#8221; <sup>1<\/sup> \u0e44\u0e14\u0e49\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14 &#8220;\u0e04\u0e27\u0e32\u0e21\u0e25\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c&#8221; (Paradigm Lag) \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e1a\u0e1a\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e15\u0e32\u0e23\u0e32\u0e07\u0e17\u0e35\u0e48 2: \u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e17\u0e22 (Evolution of the Thai Supervisor Role)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>\u0e21\u0e34\u0e15\u0e34<\/strong><\/td><td><strong>\u0e22\u0e38\u0e04\u0e1a\u0e38\u0e01\u0e40\u0e1a\u0e34\u0e01 <\/strong><br><strong>(\u0e1e.\u0e28. 2495-2540)<\/strong><\/td><td><strong>\u0e22\u0e38\u0e04\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b <\/strong><br><strong>(\u0e1e.\u0e28. 2542-\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19)<\/strong><\/td><td><strong>\u0e22\u0e38\u0e04\u0e2d\u0e19\u0e32\u0e04\u0e15 <\/strong><br><strong>(\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b)<\/strong><\/td><\/tr><tr><td><strong>\u0e04\u0e33\u0e19\u0e34\u0e22\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01<\/strong><\/td><td>\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e01\u0e32\u0e23, \u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 (Inspector) <sup>19<\/sup><\/td><td>\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19, \u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 (Supporter\/Partner) <sup>5<\/sup><\/td><td>\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22, \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14 (Researcher\/Developer) <sup>4<\/sup><\/td><\/tr><tr><td><strong>\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01<\/strong><\/td><td>\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19, \u0e2d\u0e1a\u0e23\u0e21\u0e04\u0e23\u0e39 <sup>20<\/sup><\/td><td>\u0e19\u0e34\u0e40\u0e17\u0e28, \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21, \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 <sup>2<\/sup><\/td><td>\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21, \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 <sup>4<\/sup><\/td><\/tr><tr><td><strong>\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19<\/strong><\/td><td>\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32<\/td><td>\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28, \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19<\/td><td>\u0e17\u0e31\u0e01\u0e29\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22, \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25, \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 <sup>4<\/sup><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 3: &#8220;\u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23?&#8221; &#8211; \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23 &#8220;\u0e19\u0e34\u0e40\u0e17\u0e28&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19&#8221; \u0e04\u0e33\u0e16\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e04\u0e37\u0e2d \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e33\u0e07\u0e32\u0e19\u0e19\u0e31\u0e49\u0e19 &#8220;\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23&#8221; \u0e43\u0e19\u0e42\u0e25\u0e01\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3.1 \u0e01\u0e23\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23: 3 \u0e21\u0e34\u0e15\u0e34 (Agenda-Area-Function)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e22\u0e01\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 3 \u0e21\u0e34\u0e15\u0e34\u0e40\u0e02\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 <sup>10<\/sup> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e21\u0e34\u0e15\u0e34\u0e17\u0e35\u0e48 1: \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 (Agenda Based):<\/strong> \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c O-NET, \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 Active Learning, \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 &#8220;\u0e40\u0e23\u0e35\u0e22\u0e19\u0e14\u0e35 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02&#8221; <sup>10<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e21\u0e34\u0e15\u0e34\u0e17\u0e35\u0e48 2: \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e15\u0e32\u0e21\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08 (Function Based):<\/strong> \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e01\u0e23\u0e2d\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e31\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23, \u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19, \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22, \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e <sup>10<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e21\u0e34\u0e15\u0e34\u0e17\u0e35\u0e48 3: \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e32\u0e21\u0e1a\u0e23\u0e34\u0e1a\u0e17 (Area Based):<\/strong> \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 <sup>10<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e17\u0e33\u0e21\u0e34\u0e15\u0e34\u0e43\u0e14\u0e21\u0e34\u0e15\u0e34\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e41\u0e15\u0e48\u0e04\u0e37\u0e2d &#8220;\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23&#8221; \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e34\u0e40\u0e02\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e14\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e2a\u0e23\u0e38\u0e1b\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32 <strong>\u201c\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e08\u0e30\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e44\u0e14\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u201d<\/strong> \u0e41\u0e25\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49 <strong>\u201c\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 (Function) \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e32\u0e21\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 (Area)\u201d<\/strong> <sup>10<\/sup> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e08\u0e36\u0e07\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e2a\u0e32\u0e19 &#8220;\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33&#8221; (\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22) \u0e01\u0e31\u0e1a &#8220;\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e27\u0e23\u0e17\u0e33&#8221; (\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48) \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3.2 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e30\u0e1a\u0e1a (Systematic Supervision)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08 (Function Based) \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e27\u0e07\u0e08\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e <strong>PDCA<\/strong> (Plan-Do-Check-Act) <sup>24<\/sup> \u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Plan (\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19):<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e15\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 <sup>7<\/sup> \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21) <sup>24<\/sup> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e17\u0e33 &#8220;\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32&#8221; (Supervision Plan) \u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 <sup>28<\/sup><\/li>\n\n\n\n<li><strong>Do (\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34):<\/strong> \u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19 <sup>24<\/sup> \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19, \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32, \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23, \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<\/li>\n\n\n\n<li><strong>Check (\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a):<\/strong> \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 <sup>24<\/sup> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 <sup>25<\/sup><\/li>\n\n\n\n<li><strong>Act (\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07):<\/strong> \u0e01\u0e32\u0e23\u0e19\u0e33\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32 &#8220;\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e34\u0e14&#8221; (Reflection) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 <sup>24<\/sup> \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1c\u0e25\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 <sup>25<\/sup><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e42\u0e21\u0e40\u0e14\u0e25\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 <strong>Coaching PDCAA<\/strong> <sup>29<\/sup> \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 &#8220;\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a&#8221; (Coaching) \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e43\u0e19\u0e27\u0e07\u0e08\u0e23 PDCA (\u0e42\u0e14\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21 A-Action \u0e2b\u0e23\u0e37\u0e2d A-Application \u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e38\u0e48\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01 (Active Learning) \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 <sup>29<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3.3 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d: \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e1a\u0e1a\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23&#8221;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e22\u0e38\u0e04\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 (Capacity-Building) <sup>5<\/sup> \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01 &#8220;\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a&#8221; (Checklist) <sup>7<\/sup> \u0e44\u0e1b\u0e2a\u0e39\u0e48 &#8220;\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e17\u0e2a\u0e19\u0e17\u0e19\u0e32&#8221; (Dialogue Tools) \u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. \u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a (Coaching) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e35\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 (Mentoring)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e08\u0e32\u0e01 &#8220;\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19&#8221; (Teacher) \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&#8221; (Facilitator) \u0e2b\u0e23\u0e37\u0e2d &#8220;\u0e42\u0e04\u0e49\u0e0a&#8221; 5 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e39\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a (Coaching Supervision Technique) 30 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e01:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Pre-Coaching (\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a):<\/strong> \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e39 <sup>30<\/sup><\/li>\n\n\n\n<li><strong>Coaching (\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a\/\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15):<\/strong> \u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e0a\u0e48\u0e19 &#8220;\u0e1b\u0e0f\u0e34\u0e01\u0e34\u0e23\u0e34\u0e22\u0e32\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19&#8221; (Student reaction) <sup>30<\/sup><\/li>\n\n\n\n<li><strong>Post-Coaching (\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a):<\/strong> \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23 &#8220;\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34&#8221; (Reflection) <sup>31<\/sup> \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e16\u0e32\u0e21\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e04\u0e34\u0e14 (Probing Questions) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e39\u0e44\u0e14\u0e49\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30 &#8220;\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e41\u0e01\u0e49\u0e44\u0e02\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07&#8221; <sup>30<\/sup> \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19 (\u0e04\u0e23\u0e39) \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d <sup>32<\/sup><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">2. \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (Professional Learning Community &#8211; PLC)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PLC \u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e23\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19 8 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e19\u0e33&#8221; \u0e2b\u0e23\u0e37\u0e2d &#8220;\u0e1c\u0e39\u0e49\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22&#8221; \u0e01\u0e32\u0e23\u0e17\u0e33 PLC \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 34 \u0e42\u0e14\u0e22\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30 &#8220;\u0e1e\u0e35\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07&#8221; (Mentor) \u0e2b\u0e23\u0e37\u0e2d &#8220;\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d&#8221; (Expert) 34<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e04\u0e37\u0e2d \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07 &#8220;\u0e1a\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e39\u0e17\u0e33 PLC&#8221; \u0e41\u0e15\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07 &#8220;\u0e43\u0e0a\u0e49 PLC&#8221; \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e14\u0e31\u0e07\u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e2d\u0e07 \u0e2a\u0e1e\u0e1b.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u0e40\u0e02\u0e15 1 <sup>35<\/sup> \u0e17\u0e35\u0e48\u0e01\u0e25\u0e38\u0e48\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e14\u0e49\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 PLC <em>\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e07<\/em> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e02\u0e2d\u0e07 <em>\u0e15\u0e19\u0e40\u0e2d\u0e07<\/em> \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e31\u0e0d\u0e2b\u0e32 &#8220;\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e44\u0e21\u0e48\u0e16\u0e36\u0e07\u0e04\u0e23\u0e39&#8221;, &#8220;\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e&#8221; \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e36\u0e07\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 (\u0e0b\u0e36\u0e48\u0e07\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e42\u0e21\u0e40\u0e14\u0e25 &#8220;\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32&#8221;) <sup>35<\/sup> \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23&#8221; (Academic Leader) \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07&#8221; (Model) \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 4: \u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 (Putting Theory into Practice)<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e27\u0e48\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21 \u0e15\u0e49\u0e2d\u0e07\u0e14\u0e39\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e40\u0e0a\u0e34\u0e07\u0e1a\u0e27\u0e01\u0e15\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4.1 \u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48 1: \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19 (Agenda-Based) &#8211; &#8220;\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e18\u0e34\u0e4c O-NET&#8221;<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e1a\u0e23\u0e34\u0e1a\u0e17:<\/strong> \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19 (Agenda) \u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e18\u0e34\u0e4c O-NET <sup>10<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 (The How):<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e30\u0e2b\u0e25\u0e35\u0e01\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e32\u0e23 &#8220;\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23&#8221; (Top-down) \u0e43\u0e2b\u0e49\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21 <sup>10<\/sup> \u0e41\u0e15\u0e48\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35 &#8220;\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e23\u0e30\u0e14\u0e21\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14&#8221; (Bottom-up facilitation) \u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e23\u0e39\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 <sup>10<\/sup><\/li>\n\n\n\n<li><strong>\u0e1a\u0e17\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e2a\u0e33\u0e04\u0e31\u0e0d:<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e08\u0e30\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01&#8221; (Facilitator) \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e33\u0e16\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e27\u0e48\u0e32 <strong>\u201c\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e43\u0e2b\u0e49\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1c\u0e25\u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19?\u201d<\/strong> <sup>10<\/sup><\/li>\n\n\n\n<li><strong>\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c:<\/strong> \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e33\u0e16\u0e32\u0e21\u0e19\u0e35\u0e49\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48 &#8220;\u0e17\u0e38\u0e01\u0e04\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e04\u0e34\u0e14 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e17\u0e33&#8221; <sup>10<\/sup> \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 (Area-Based) \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23\u0e08\u0e32\u0e01\u0e1a\u0e19\u0e25\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e08\u0e32\u0e01 &#8220;\u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21&#8221; (Controller) \u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23&#8221; (Process Designer) \u0e43\u0e2b\u0e49\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4.2 \u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48 2: \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e43\u0e2b\u0e21\u0e48 (Pedagogy Implementation) &#8211; &#8220;Active Learning \u0e41\u0e25\u0e30 GPAS 5 Steps&#8221;<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e1a\u0e23\u0e34\u0e1a\u0e17:<\/strong> \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e28\u0e15\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 21 \u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e40\u0e19\u0e49\u0e19 &#8220;\u0e01\u0e32\u0e23\u0e08\u0e33&#8221; (Rote) \u0e44\u0e1b\u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e32\u0e23\u0e04\u0e34\u0e14&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21&#8221; <sup>11<\/sup><\/li>\n\n\n\n<li><strong>\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c:<\/strong> \u0e16\u0e39\u0e01\u0e27\u0e32\u0e07\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48&#8221; (Area-based Mechanism) \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 (\u0e40\u0e0a\u0e48\u0e19 Active Learning, GPAS 5 Steps) \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 <sup>11<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 (The How):<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e08\u0e32\u0e01 &#8220;\u0e1c\u0e39\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21&#8221; (Monitor) \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 <strong>&#8220;\u0e42\u0e04\u0e49\u0e0a\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23&#8221; (Academic Coach)<\/strong> <sup>11<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34:<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 (Upskill) \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e43\u0e2b\u0e21\u0e48\u0e46 <sup>11<\/sup> \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e42\u0e04\u0e49\u0e0a\u0e0a\u0e34\u0e48\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48&#8221; <sup>36<\/sup> \u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e39 (Co-design) \u0e40\u0e1e\u0e37\u0e48\u0e2d &#8220;\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&#8221; (Learning Designer) <sup>11<\/sup><\/li>\n\n\n\n<li><strong>\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e35\u0e48\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07:<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e19\u0e31\u0e01\u0e41\u0e1b\u0e25&#8221; (Translator) \u0e2b\u0e23\u0e37\u0e2d &#8220;\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49&#8221; (Knowledge Broker) <sup>11<\/sup> \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07 &#8220;\u0e41\u0e1b\u0e25&#8221; \u0e20\u0e32\u0e29\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e17\u0e35\u0e48\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19 (\u0e40\u0e0a\u0e48\u0e19 GPAS 5 Steps) <sup>11<\/sup> \u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19&#8221; \u0e17\u0e35\u0e48\u0e04\u0e23\u0e39\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e42\u0e14\u0e22\u0e15\u0e49\u0e2d\u0e07 &#8220;\u0e22\u0e36\u0e14\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e10\u0e32\u0e19&#8221; \u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e19\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 <sup>36<\/sup> \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4.3 \u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48 3: \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e23\u0e39\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e01\u0e25\u0e38\u0e48\u0e21 (Teacher Development) &#8211; &#8220;\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19 PLC \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32&#8221;<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e1a\u0e23\u0e34\u0e1a\u0e17:<\/strong> \u0e04\u0e23\u0e39\u0e1e\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e0b\u0e31\u0e1a\u0e0b\u0e49\u0e2d\u0e19 \u0e41\u0e15\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e20\u0e32\u0e22\u0e43\u0e19 (Internal Supervision) \u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32 <sup>8<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 (The How):<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1e\u0e35\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07&#8221; (Mentor) \u0e41\u0e25\u0e30 &#8220;\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d&#8221; (Expert) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e07 PLC \u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39 <sup>34<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34:<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 PLC \u0e01\u0e31\u0e1a\u0e04\u0e23\u0e39 (\u0e40\u0e0a\u0e48\u0e19 Model Teacher, Buddy) <sup>34<\/sup> \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 (Observe) -&gt; \u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 (Reflect) -&gt; \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 (Study) -&gt; \u0e41\u0e25\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 (Revise) <sup>34<\/sup><\/li>\n\n\n\n<li><strong>\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c:<\/strong> \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e20\u0e32\u0e22\u0e43\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e02\u0e36\u0e49\u0e19 <sup>10<\/sup> \u0e04\u0e23\u0e39\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e14\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e19 <sup>8<\/sup> \u0e41\u0e25\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e15\u0e23\u0e07\u0e08\u0e38\u0e14\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1c\u0e48\u0e32\u0e19 PLC \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 &#8220;\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25&#8221; (Individual) \u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 &#8220;\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a&#8221; (Systemic) \u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e01\u0e27\u0e48\u0e32<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 5: \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19 &#8211; \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07 \u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e16\u0e32\u0e21 &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21&#8221; \u0e16\u0e39\u0e01\u0e16\u0e32\u0e21\u0e02\u0e36\u0e49\u0e19 \u0e21\u0e32\u0e08\u0e32\u0e01 &#8220;\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07&#8221; (The Gap) \u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 &#8220;\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07&#8221; \u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32 &#8220;\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e23\u0e34\u0e07&#8221;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5.1 \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e32\u0e01 &#8220;\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19&#8221;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07 (What they want):<\/strong> \u0e04\u0e23\u0e39\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 &#8220;\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23&#8221; \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e25\u0e36\u0e01\u0e0b\u0e36\u0e49\u0e07 <sup>3<\/sup> \u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23&#8221; \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 <sup>3<\/sup> \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e46 (\u0e40\u0e0a\u0e48\u0e19 AI) \u0e21\u0e32\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49 <sup>3<\/sup> \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e04\u0e37\u0e2d \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e19\u0e17\u0e35\u0e48 &#8220;\u0e21\u0e35\u0e21\u0e19\u0e38\u0e29\u0e22\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e35&#8221; \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e23\u0e21\u0e13\u0e4c \u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e08\u0e38\u0e14\u0e2d\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30 &#8220;\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19&#8221; \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23 <sup>21<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07 (What they get &#8211; The Gap):<\/strong> \u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 <sup>21<\/sup> \u0e44\u0e14\u0e49\u0e0a\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19 &#8220;\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07&#8221; \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e01\u0e31\u0e07\u0e27\u0e25\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07<\/strong>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e19\u0e34\u0e40\u0e17\u0e28\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c: \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a <strong>&#8220;\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14&#8221;<\/strong><\/li>\n\n\n\n<li><strong>\u0e2a\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07<\/strong>\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c: \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a <strong>&#8220;\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07&#8221;<\/strong><\/li>\n\n\n\n<li>\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e21\u0e2b\u0e32\u0e28\u0e32\u0e25\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 &#8220;\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07 (\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14)&#8221; \u0e01\u0e31\u0e1a &#8220;\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07 (\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07)&#8221; \u0e19\u0e35\u0e49 <sup>21<\/sup> \u0e04\u0e37\u0e2d &#8220;\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d&#8221; (Credibility Gap) \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5.2 \u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e1a: \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e27\u0e48\u0e32 &#8220;\u0e17\u0e33\u0e44\u0e21\u0e04\u0e23\u0e39\u0e16\u0e36\u0e07\u0e44\u0e21\u0e48\u0e0a\u0e2d\u0e1a \u0e28\u0e19.?&#8221;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07 \u0e08\u0e36\u0e07\u0e40\u0e01\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e1a \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e04\u0e23\u0e39\u0e43\u0e19\u0e40\u0e27\u0e17\u0e35\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 <sup>1<\/sup> \u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e35\u0e48\u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e1a\u0e32\u0e07\u0e04\u0e19 &#8220;\u0e0a\u0e2d\u0e1a\u0e17\u0e33\u0e15\u0e31\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e19\u0e32\u0e22\u0e2a\u0e31\u0e48\u0e07\u0e07\u0e32\u0e19\u0e04\u0e23\u0e39&#8221; \u0e21\u0e32\u0e08\u0e32\u0e01:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19:<\/strong> \u0e04\u0e23\u0e39\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e32\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30 &#8220;\u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23&#8221; <sup>1<\/sup> \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 PA \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22 <sup>1<\/sup> \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01 &#8220;\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23&#8221; \u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19&#8221;<\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e15\u0e15\u0e32 (Ego):<\/strong> \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 &#8220;\u0e27\u0e32\u0e17\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e27\u0e22\u0e2b\u0e23\u0e39&#8221; \u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e22\u0e32\u0e01, \u0e01\u0e32\u0e23\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e15\u0e32\u0e2a\u0e39\u0e07 (EGO \u0e2a\u0e39\u0e07), \u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39 <sup>1<\/sup><\/li>\n\n\n\n<li><strong>\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e34\u0e14\u0e40\u0e1a\u0e37\u0e2d\u0e19:<\/strong> \u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\u0e15\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e31\u0e01\u0e1c\u0e39\u0e01\u0e15\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23 &#8220;\u0e21\u0e32\u0e15\u0e23\u0e27\u0e08\u0e07\u0e32\u0e19&#8221; \u0e2b\u0e23\u0e37\u0e2d &#8220;\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23&#8221; <sup>4<\/sup> \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23 &#8220;\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19&#8221;<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 &#8220;\u0e40\u0e08\u0e15\u0e19\u0e32&#8221; (Intention) \u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 &#8220;\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49&#8221; (Perception) \u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39 \u0e0b\u0e36\u0e48\u0e07\u0e16\u0e39\u0e01\u0e15\u0e2d\u0e01\u0e22\u0e49\u0e33\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1c\u0e34\u0e14\u0e1e\u0e25\u0e32\u0e14 <sup>1<\/sup> \u0e41\u0e25\u0e30\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e34\u0e14\u0e40\u0e1a\u0e37\u0e2d\u0e19 (\u0e14\u0e31\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 6) \u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e14\u0e39\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e07\u0e32\u0e19&#8221; \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07\u0e32\u0e19&#8221;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5.3 \u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e32\u0e01 &#8220;\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32&#8221;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07 (What they want):<\/strong> \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30 <strong>&#8220;\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32&#8221; (Development Partner)<\/strong> <sup>6<\/sup> \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07 4 \u0e14\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e01 <sup>6<\/sup> \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23:<\/strong> \u0e15\u0e49\u0e2d\u0e07\u0e41\u0e15\u0e01\u0e09\u0e32\u0e19\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32, \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e24\u0e29\u0e0e\u0e35 (\u0e19\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21) \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21&#8221; (\u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19) \u0e17\u0e35\u0e48\u0e04\u0e23\u0e39\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 <sup>6<\/sup><\/li>\n\n\n\n<li><strong>\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19:<\/strong> \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e40\u0e01\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 10 \u0e17\u0e34\u0e28&#8221; <sup>6<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d:<\/strong> \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e48\u0e07&#8221; \u0e17\u0e35\u0e48\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e35\u0e48 &#8220;\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07&#8221; \u0e15\u0e32\u0e21\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 <sup>6<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49:<\/strong> \u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2a\u0e21\u0e2d \u0e41\u0e25\u0e30\u0e21\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e21\u0e32\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19 <sup>6<\/sup><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01:<\/strong> \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e30\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e21\u0e04\u0e21\u0e27\u0e48\u0e32 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c &#8220;\u0e04\u0e27\u0e23\u0e21\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e39\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e04\u0e19\u0e25\u0e30\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e43\u0e2b\u0e49\u0e41\u0e15\u0e48\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e32\u0e40\u0e2d\u0e07&#8221; <sup>6<\/sup> \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07 &#8220;\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01&#8221; (Proactive Leader) \u0e17\u0e35\u0e48\u0e21\u0e35 &#8220;\u0e02\u0e2d\u0e07&#8221; \u0e21\u0e32\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48 &#8220;\u0e1c\u0e39\u0e49\u0e15\u0e32\u0e21&#8221; (Follower) \u0e17\u0e35\u0e48\u0e23\u0e2d\u0e2a\u0e48\u0e07\u0e2a\u0e32\u0e23\u0e08\u0e32\u0e01\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e15\u0e32\u0e23\u0e32\u0e07\u0e17\u0e35\u0e48 3: \u0e2a\u0e23\u0e38\u0e1b\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07 (The Expectation vs. Reality Gap)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>\u0e21\u0e34\u0e15\u0e34<\/strong><\/td><td><strong>\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e32\u0e01\u0e04\u0e23\u0e39\/\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/strong><\/td><td><strong>\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49 (\u0e08\u0e32\u0e01 )<\/strong><\/td><\/tr><tr><td><strong>\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<\/strong><\/td><td>\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23, \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d, \u0e17\u0e35\u0e48\u0e1e\u0e36\u0e48\u0e07 <sup>3<\/sup><\/td><td>\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07: \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 <sup>21<\/sup><br>(\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e16\u0e39\u0e01\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e40\u0e01\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e39 <sup>1<\/sup>)<\/td><\/tr><tr><td><strong>\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/strong><\/td><td>\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23, \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14, \u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 <sup>6<\/sup><\/td><td>\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07: \u0e1c\u0e39\u0e49\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23, \u0e40\u0e08\u0e49\u0e32\u0e19\u0e32\u0e22, Ego \u0e2a\u0e39\u0e07 <sup>1<\/sup><\/td><\/tr><tr><td><strong>\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19<\/strong><\/td><td>\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32, \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 <sup>3<\/sup><\/td><td>\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07: \u0e40\u0e19\u0e49\u0e19\u0e15\u0e23\u0e27\u0e08\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23, \u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 <sup>4<\/sup><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e32\u0e23\u0e32\u0e07\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d &#8220;\u0e2b\u0e31\u0e27\u0e43\u0e08&#8221; \u0e02\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e21\u0e31\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 &#8220;\u0e17\u0e33\u0e44\u0e21&#8221; \u0e04\u0e33\u0e16\u0e32\u0e21 &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21&#8221; \u0e08\u0e36\u0e07\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e19\u0e17\u0e38\u0e01\u0e21\u0e34\u0e15\u0e34\u0e17\u0e35\u0e48\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07 \u0e01\u0e25\u0e31\u0e1a\u0e21\u0e35 &#8220;\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49&#8221; \u0e17\u0e35\u0e48\u0e15\u0e23\u0e07\u0e01\u0e31\u0e19\u0e02\u0e49\u0e32\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e0a\u0e34\u0e07<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 6: \u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 (The Vicious Cycle)<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07&#8221; \u0e43\u0e19\u0e15\u0e32\u0e23\u0e32\u0e07\u0e17\u0e35\u0e48 3 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e21\u0e32\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e23\u0e31\u0e14\u0e15\u0e23\u0e36\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49\u0e44\u0e27\u0e49<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6.1 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 <sup>4<\/sup> \u0e1e\u0e1a\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e2b\u0e25\u0e31\u0e01 4 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 (Non-Supervisory Tasks):<\/strong> \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e23\u0e30\u0e1a\u0e38\u0e0b\u0e49\u0e33\u0e46 \u201c\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e41\u0e17\u0e23\u0e01\u0e41\u0e25\u0e30\u0e40\u0e23\u0e48\u0e07\u0e23\u0e35\u0e1a\u0e21\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e34\u0e49\u0e07\u0e07\u0e32\u0e19\u0e19\u0e34\u0e40\u0e17\u0e28\u0e44\u0e1b\u201d <sup>18<\/sup> \u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 2.2 \u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e16\u0e39\u0e01\u0e1d\u0e31\u0e07\u0e44\u0e27\u0e49\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 <sup>15<\/sup><\/li>\n\n\n\n<li><strong>\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23 (Resource Constraints):<\/strong> \u201c\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e43\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e1b\u0e35 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1b\u0e35\u0e25\u0e30 2-3 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u201d <sup>18<\/sup> \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 &#8220;\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e22\u0e34\u0e48\u0e07\u0e2b\u0e48\u0e32\u0e07\u0e44\u0e01\u0e25\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e21\u0e35\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e25\u0e22&#8230;. \u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27&#8221; <sup>18<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 (Personnel Shortage):<\/strong> \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e27\u0e48\u0e32\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,000 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 <sup>4<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d (Lack of Priority):<\/strong> \u201c\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u201d <sup>18<\/sup><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>6.2 \u0e27\u0e07\u0e08\u0e23\u0e44\u0e21\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c (The Vicious Cycle)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e02\u0e49\u0e2d 6.1 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e22\u0e01\u0e01\u0e31\u0e19 \u0e41\u0e15\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e23\u0e30\u0e1a\u0e1a&#8221; \u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07 &#8220;\u0e27\u0e07\u0e08\u0e23\u0e44\u0e21\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c&#8221; (Vicious Cycle) \u0e17\u0e35\u0e48\u0e17\u0e33\u0e25\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19:<\/strong> \u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 <sup>4<\/sup> \u0e1c\u0e19\u0e27\u0e01\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 <sup>15<\/sup> \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 <sup>18<\/sup><\/li>\n\n\n\n<li><strong>\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48:<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e08\u0e33\u0e19\u0e27\u0e19\u0e19\u0e49\u0e2d\u0e22 \u0e15\u0e49\u0e2d\u0e07\u0e41\u0e1a\u0e01\u0e23\u0e31\u0e1a &#8220;\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e07\u0e32\u0e19\u0e41\u0e17\u0e23\u0e01&#8221; <sup>18<\/sup> \u0e08\u0e19\u0e25\u0e49\u0e19\u0e21\u0e37\u0e2d<\/li>\n\n\n\n<li><strong>\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a:<\/strong> \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e02\u0e32\u0e14\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e41\u0e25\u0e30\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e19\u0e34\u0e40\u0e17\u0e28 <sup>18<\/sup><\/li>\n\n\n\n<li><strong>\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c:<\/strong> \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c &#8220;\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2d\u0e2d\u0e01\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e25\u0e22&#8221; <sup>18<\/sup> \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1b\u0e35\u0e25\u0e30 2-3 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49 &#8220;\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e31\u0e0d\u0e2b\u0e32&#8221; <sup>18<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49:<\/strong> \u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 (\u0e14\u0e31\u0e07\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 5) \u0e08\u0e36\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e21\u0e32 &#8220;\u0e15\u0e32\u0e21\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23&#8221; <sup>4<\/sup> \u0e2b\u0e23\u0e37\u0e2d &#8220;\u0e2a\u0e31\u0e48\u0e07\u0e07\u0e32\u0e19&#8221; <sup>1<\/sup><\/li>\n\n\n\n<li><strong>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19:<\/strong> \u0e2a\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07\u0e08\u0e36\u0e07\u0e16\u0e39\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e44\u0e27\u0e49\u0e41\u0e04\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a &#8220;\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07&#8221; <sup>21<\/sup><\/li>\n\n\n\n<li><strong>\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22:<\/strong> \u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d <sup>4<\/sup> \u0e04\u0e19\u0e40\u0e01\u0e48\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c <sup>4<\/sup> -&gt; \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 <sup>4<\/sup> \u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e02\u0e36\u0e49\u0e19 -&gt; \u0e27\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e08\u0e38\u0e14\u0e17\u0e35\u0e48 1<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e27\u0e07\u0e08\u0e23\u0e19\u0e35\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32 &#8220;\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b&#8221; (\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 7) \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e01\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e14\u0e34\u0e21\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e25\u0e32\u0e22\u0e27\u0e07\u0e08\u0e23\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23 &#8220;\u0e15\u0e31\u0e14&#8221; \u0e27\u0e07\u0e08\u0e23\u0e19\u0e35\u0e49\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 7: \u0e1a\u0e17\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e32\u0e04\u0e15 &#8211; &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c&#8221; \u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e04\u0e15\u0e34, \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19, \u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07, \u0e41\u0e25\u0e30\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21&#8221; \u0e41\u0e25\u0e30\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>7.1 \u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e04\u0e33\u0e15\u0e2d\u0e1a: &#8220;\u0e15\u0e01\u0e25\u0e07\u0e41\u0e25\u0e49\u0e27&#8230;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21?&#8221;<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d &#8220;\u0e15\u0e23\u0e27\u0e08&#8221; \u0e2b\u0e23\u0e37\u0e2d &#8220;\u0e2a\u0e31\u0e48\u0e07&#8221; \u0e41\u0e15\u0e48\u0e21\u0e35\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 3 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e41\u0e17\u0e19\u0e44\u0e14\u0e49:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>\u0e21\u0e35\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e19\u0e31\u0e01\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07&#8221; (The Linker):<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e04\u0e37\u0e2d\u0e01\u0e25\u0e44\u0e01\u0e40\u0e14\u0e35\u0e22\u0e27\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 &#8220;\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22&#8221; (Policy) \u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07 <sup>2<\/sup> \u0e01\u0e31\u0e1a &#8220;\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34&#8221; (Practice) \u0e08\u0e23\u0e34\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 <sup>11<\/sup> \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e04\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 (\u0e40\u0e0a\u0e48\u0e19 Active Learning) \u0e21\u0e32 &#8220;\u0e41\u0e1b\u0e25&#8221; \u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 <sup>11<\/sup><\/li>\n\n\n\n<li><strong>\u0e21\u0e35\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14&#8221; (The Thought Partner):<\/strong> \u0e43\u0e19\u0e10\u0e32\u0e19\u0e30 &#8220;\u0e01\u0e31\u0e25\u0e22\u0e32\u0e13\u0e21\u0e34\u0e15\u0e23&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e42\u0e04\u0e49\u0e0a\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23&#8221; <sup>11<\/sup> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19, \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19, \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 PLC \u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 <sup>5<\/sup><\/li>\n\n\n\n<li><strong>\u0e21\u0e35\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32&#8221; (The R&amp;D Specialist):<\/strong> \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 (R&amp;D) <sup>14<\/sup> \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 (\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25, AI) <sup>22<\/sup> \u0e21\u0e32\u0e2a\u0e39\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 <sup>2<\/sup><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>7.2 \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e: \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e40\u0e14\u0e34\u0e21\u0e44\u0e21\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33 3 \u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e44\u0e14\u0e49 (\u0e14\u0e31\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e43\u0e19 &#8220;\u0e27\u0e07\u0e08\u0e23\u0e44\u0e21\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c&#8221;) <sup>4<\/sup> \u0e19\u0e33\u0e21\u0e32\u0e2a\u0e39\u0e48\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e14\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e08\u0e32\u0e01\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 <sup>4<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (Role Change):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e08\u0e30\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19:<\/strong> \u0e1c\u0e39\u0e49\u0e44\u0e1b\u0e2d\u0e1a\u0e23\u0e21\u0e04\u0e23\u0e39 (Trainer)<\/li>\n\n\n\n<li><strong>\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19:<\/strong> <strong>\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32<\/strong> (Researcher\/Developer), <strong>\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14<\/strong> (Consultant\/Partner), \u0e41\u0e25\u0e30 <strong>\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49<\/strong> (Knowledge Linker) \u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 <sup>4<\/sup><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. \u0e17\u0e31\u0e01\u0e29\u0e30\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 (New Skills):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e07 <sup>4<\/sup><\/li>\n\n\n\n<li>\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e2b\u0e21\u0e48 <sup>4<\/sup><\/li>\n\n\n\n<li>\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (Digital Literacy) \u0e41\u0e25\u0e30 AI <sup>4<\/sup><\/li>\n\n\n\n<li>\u0e17\u0e31\u0e01\u0e29\u0e30\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 (\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a B2) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 <sup>4<\/sup><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e39\u0e48\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (New Entry Tracks):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u0e41\u0e17\u0e23\u0e47\u0e01 1 (\u0e40\u0e14\u0e34\u0e21):<\/strong> \u0e23\u0e30\u0e1a\u0e1a &#8220;Hunting System&#8221; \u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e04\u0e23\u0e39\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e2a\u0e39\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 <sup>4<\/sup><\/li>\n\n\n\n<li><strong>\u0e41\u0e17\u0e23\u0e47\u0e01 2 (\u0e43\u0e2b\u0e21\u0e48):<\/strong> \u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 (\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e23\u0e39) \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e2a\u0e39\u0e07 (\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e1a \u0e1b.\u0e42\u0e17\/\u0e40\u0e2d\u0e01, \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 5 \u0e1b\u0e35, \u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 B2, \u0e21\u0e35\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c) <sup>4<\/sup><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. \u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e21\u0e48 (New Compensation):<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e04\u0e19\u0e40\u0e01\u0e48\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 \u0e1b.\u0e42\u0e17 32,000 \u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30 \u0e1b.\u0e40\u0e2d\u0e01 35,000 \u0e1a\u0e32\u0e17 <sup>4<\/sup><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e23\u0e30\u0e1a\u0e1a &#8220;\u0e17\u0e48\u0e2d\u0e2a\u0e48\u0e07&#8221; (Pipeline) \u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e34\u0e21 (\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e04\u0e23\u0e39\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c) \u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35 &#8220;\u0e17\u0e31\u0e01\u0e29\u0e30\u0e43\u0e2b\u0e21\u0e48&#8221; (\u0e27\u0e34\u0e08\u0e31\u0e22, \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25, \u0e20\u0e32\u0e29\u0e32) \u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e15\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 21 \u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b <sup>4<\/sup> \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07 &#8220;\u0e41\u0e17\u0e23\u0e47\u0e01 2&#8221; \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23 &#8220;\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32&#8221; (Import) \u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e35\u0e48\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30 &#8220;\u0e08\u0e48\u0e32\u0e22&#8221; (Compensate) \u0e43\u0e19\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e25\u0e32\u0e14 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23 &#8220;\u0e23\u0e37\u0e49\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07&#8221; (Deconstruct\/Reconstruct) \u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e2a\u0e23\u0e38\u0e1b \u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07 &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c&#8221; \u0e41\u0e25\u0e30\u0e04\u0e33\u0e15\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e33\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 &#8220;\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21&#8221; \u0e08\u0e36\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e35\u0e49 \u0e2b\u0e32\u0e01\u0e17\u0e33\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e08\u0e30\u0e16\u0e39\u0e01\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22&#8221; \u0e41\u0e25\u0e30 &#8220;\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14&#8221; \u0e17\u0e35\u0e48\u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e39\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07 <sup>6<\/sup> \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e25\u0e49\u0e21\u0e40\u0e2b\u0e25\u0e27 \u0e1e\u0e27\u0e01\u0e40\u0e02\u0e32\u0e01\u0e47\u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 &#8220;\u0e27\u0e07\u0e08\u0e23\u0e44\u0e21\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c&#8221; (\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 6.2) \u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 &#8220;\u0e1c\u0e39\u0e49\u0e15\u0e32\u0e21\u0e07\u0e32\u0e19&#8221; \u0e17\u0e35\u0e48\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d <sup>4<\/sup> \u0e41\u0e25\u0e30\u0e04\u0e33\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 &#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21&#8221; \u0e01\u0e47\u0e08\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e16\u0e39\u0e01\u0e16\u0e32\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e01\u0e31\u0e07\u0e02\u0e32<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Works cited<\/strong><\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e17\u0e33\u0e44\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e33\u0e15\u0e31\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e19\u0e32\u0e22\u0e2a\u0e31\u0e48\u0e07\u0e07\u0e32\u0e19 &#8230;, accessed November 13, 2025, <a href=\"https:\/\/pantip.com\/topic\/42388819\">https:\/\/pantip.com\/topic\/42388819<\/a><\/li>\n\n\n\n<li>\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c: \u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u00bb &#8211; Digital Learning Classroom, accessed November 13, 2025, <a href=\"https:\/\/krukob.com\/web\/sv-33\/\">https:\/\/krukob.com\/web\/sv-33\/<\/a><\/li>\n\n\n\n<li>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e22\u0e38\u0e04\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23 &#8230;, accessed November 13, 2025, <a href=\"https:\/\/krukob.com\/web\/sv-11\/\">https:\/\/krukob.com\/web\/sv-11\/<\/a><\/li>\n\n\n\n<li>\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e17\u0e22: \u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u00bb, accessed November 13, 2025, <a href=\"https:\/\/krukob.com\/web\/sv-18\/\">https:\/\/krukob.com\/web\/sv-18\/<\/a><\/li>\n\n\n\n<li>\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e0a\u0e35\u0e49\u0e41\u0e19\u0e30\u0e2a\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08: \u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e42\u0e04\u0e49\u0e0a \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23 &#8230;, accessed November 13, 2025, <a href=\"https:\/\/krukob.com\/web\/sv-39\/\">https:\/\/krukob.com\/web\/sv-39\/<\/a><\/li>\n\n\n\n<li>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e22\u0e38\u0e04\u0e02\u0e2d\u0e07 &#8230;, accessed November 13, 2025, <a href=\"https:\/\/krukob.com\/web\/sv-12\/\">https:\/\/krukob.com\/web\/sv-12\/<\/a><\/li>\n\n\n\n<li>\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c, accessed November 13, 2025, <a href=\"http:\/\/www.cpn2.go.th\/wp-content\/uploads\/2020\/07\/%E0%B8%84%E0%B8%B9%E0%B9%88%E0%B8%A1%E0%B8%B7%E0%B8%AD%E0%B8%9B%E0%B8%8F%E0%B8%B4%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%87%E0%B8%B2%E0%B8%99%E0%B8%A7%E0%B8%A3%E0%B8%A3%E0%B8%93%E0%B9%8C%E0%B8%A4%E0%B8%97%E0%B8%B1%E0%B8%A2.pdf\">http:\/\/www.cpn2.go.th\/wp-content\/uploads\/2020\/07\/%E0%B8%84%E0%B8%B9%E0%B9%88%E0%B8%A1%E0%B8%B7%E0%B8%AD%E0%B8%9B%E0%B8%8F%E0%B8%B4%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B8%87%E0%B8%B2%E0%B8%99%E0%B8%A7%E0%B8%A3%E0%B8%A3%E0%B8%93%E0%B9%8C%E0%B8%A4%E0%B8%97%E0%B8%B1%E0%B8%A2.pdf<\/a><\/li>\n\n\n\n<li>\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 &#8211; \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e20\u0e32\u0e04 9, accessed November 13, 2025, <a href=\"http:\/\/www.reo9.obec.in.th\/gis\/eoffice\/10000005tbl_orgdownload\/20211027102947mr1gnTS..pdf\">http:\/\/www.reo9.obec.in.th\/gis\/eoffice\/10000005tbl_orgdownload\/20211027102947mr1gnTS..pdf<\/a><\/li>\n\n\n\n<li>\u0e2a\u0e2a\u0e27\u0e17. \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u201c\u0e1c\u0e39\u0e49\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49, accessed November 13, 2025, <a href=\"https:\/\/www.ipst.ac.th\/news\/76392\/coaching.html\">https:\/\/www.ipst.ac.th\/news\/76392\/coaching.html<\/a><\/li>\n\n\n\n<li>\u0e02\u0e2d\u0e1a\u0e02\u0e48\u0e32\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 (\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2) \u00bb &#8211; Digital Learning Classroom, accessed November 13, 2025, <a href=\"https:\/\/krukob.com\/web\/sv-9\/\">https:\/\/krukob.com\/web\/sv-9\/<\/a><\/li>\n\n\n\n<li>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c: \u0e01\u0e25\u0e44\u0e01\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01 \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23 &#8230;, accessed November 13, 2025, <a href=\"https:\/\/mgronline.com\/qol\/detail\/9680000062315\">https:\/\/mgronline.com\/qol\/detail\/9680000062315<\/a><\/li>\n\n\n\n<li>2. \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 &#8211; \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c 2567, accessed November 13, 2025, <a href=\"https:\/\/sv1.esdc.go.th\/%E0%B8%AB%E0%B8%99%E0%B8%B2%E0%B9%81%E0%B8%A3%E0%B8%81\/%E0%B8%A3%E0%B8%B0%E0%B8%A2%E0%B8%B0%E0%B8%97-1-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%A2%E0%B8%A1%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B8%AD%E0%B8%99%E0%B9%80%E0%B8%82%E0%B8%B2%E0%B8%A3%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%92%E0%B8%99%E0%B8%B2\/2-%E0%B8%A1%E0%B8%B2%E0%B8%95%E0%B8%A3%E0%B8%90%E0%B8%B2%E0%B8%99%E0%B8%95%E0%B8%B3%E0%B9%81%E0%B8%AB%E0%B8%99%E0%B8%87\">https:\/\/sv1.esdc.go.th\/%E0%B8%AB%E0%B8%99%E0%B8%B2%E0%B9%81%E0%B8%A3%E0%B8%81\/%E0%B8%A3%E0%B8%B0%E0%B8%A2%E0%B8%B0%E0%B8%97-1-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%A2%E0%B8%A1%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B8%AD%E0%B8%99%E0%B9%80%E0%B8%82%E0%B8%B2%E0%B8%A3%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%92%E0%B8%99%E0%B8%B2\/2-%E0%B8%A1%E0%B8%B2%E0%B8%95%E0%B8%A3%E0%B8%90%E0%B8%B2%E0%B8%99%E0%B8%95%E0%B8%B3%E0%B9%81%E0%B8%AB%E0%B8%99%E0%B8%87<\/a><\/li>\n\n\n\n<li>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 (\u0e27.PA) \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c &#8211; PubHTML5, accessed November 13, 2025, <a href=\"https:\/\/pubhtml5.com\/jibv\/kjih\/\">https:\/\/pubhtml5.com\/jibv\/kjih\/<\/a><\/li>\n\n\n\n<li>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e40\u0e40\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01 &#8211; \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 &#8230;, accessed November 13, 2025, <a href=\"https:\/\/www.chan2.go.th\/wp-content\/uploads\/2024\/06\/OIT-10-%E0%B8%84%E0%B8%B9%E0%B9%88%E0%B8%A1%E0%B8%B7%E0%B8%AD%E0%B8%81%E0%B8%A5%E0%B8%B8%E0%B9%88%E0%B8%A1%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8-2567.pdf\">https:\/\/www.chan2.go.th\/wp-content\/uploads\/2024\/06\/OIT-10-%E0%B8%84%E0%B8%B9%E0%B9%88%E0%B8%A1%E0%B8%B7%E0%B8%AD%E0%B8%81%E0%B8%A5%E0%B8%B8%E0%B9%88%E0%B8%A1%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8-2567.pdf<\/a><\/li>\n\n\n\n<li>\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e09\u0e1a\u0e31\u0e1a\u0e19\u0e35\u0e49 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 &#8211; \u0e2a\u0e1e\u0e1b.\u0e1e\u0e31\u0e07\u0e07\u0e32, accessed November 13, 2025, <a href=\"https:\/\/www.phangngaedarea.go.th\/site\/wp-content\/uploads\/ita\/67\/O10\/supervision\/%E0%B8%99%E0%B8%95.-%E0%B8%9E%E0%B8%88%E0%B8%A1%E0%B8%B2%E0%B8%A8.pdf\">https:\/\/www.phangngaedarea.go.th\/site\/wp-content\/uploads\/ita\/67\/O10\/supervision\/%E0%B8%99%E0%B8%95.-%E0%B8%9E%E0%B8%88%E0%B8%A1%E0%B8%B2%E0%B8%A8.pdf<\/a><\/li>\n\n\n\n<li>3. \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 &#8211; \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c 2567, accessed November 13, 2025, <a href=\"https:\/\/sv1.esdc.go.th\/%E0%B8%AB%E0%B8%99%E0%B8%B2%E0%B9%81%E0%B8%A3%E0%B8%81\/%E0%B8%A3%E0%B8%B0%E0%B8%A2%E0%B8%B0%E0%B8%97-1-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%A2%E0%B8%A1%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B8%AD%E0%B8%99%E0%B9%80%E0%B8%82%E0%B8%B2%E0%B8%A3%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%92%E0%B8%99%E0%B8%B2\/3-%E0%B8%A1%E0%B8%B2%E0%B8%95%E0%B8%A3%E0%B8%90%E0%B8%B2%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9B%E0%B8%8F%E0%B8%9A%E0%B8%95%E0%B8%87%E0%B8%B2%E0%B8%99\">https:\/\/sv1.esdc.go.th\/%E0%B8%AB%E0%B8%99%E0%B8%B2%E0%B9%81%E0%B8%A3%E0%B8%81\/%E0%B8%A3%E0%B8%B0%E0%B8%A2%E0%B8%B0%E0%B8%97-1-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%A2%E0%B8%A1%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B8%AD%E0%B8%99%E0%B9%80%E0%B8%82%E0%B8%B2%E0%B8%A3%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%92%E0%B8%99%E0%B8%B2\/3-%E0%B8%A1%E0%B8%B2%E0%B8%95%E0%B8%A3%E0%B8%90%E0%B8%B2%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9B%E0%B8%8F%E0%B8%9A%E0%B8%95%E0%B8%87%E0%B8%B2%E0%B8%99<\/a><\/li>\n\n\n\n<li>\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c &#8211; \u0e15\u0e32\u0e01 \u0e40\u0e02\u0e15 2, accessed November 13, 2025, <a href=\"http:\/\/www.takesa2.go.th\/download\/manual\/nitad.pdf\">http:\/\/www.takesa2.go.th\/download\/manual\/nitad.pdf<\/a><\/li>\n\n\n\n<li>\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28 &#8211; \u0e19\u0e32\u0e19\u0e32\u0e2a\u0e32\u0e23\u0e30 \u0e01\u0e31\u0e1a\u0e04\u0e23\u0e39\u0e44\u0e1e\u0e11\u0e39\u0e23\u0e22\u0e4c &#8211; GotoKnow, accessed November 13, 2025, <a href=\"https:\/\/www.gotoknow.org\/posts\/204579\">https:\/\/www.gotoknow.org\/posts\/204579<\/a><\/li>\n\n\n\n<li>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48: \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e43\u0e19\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 &#8211; \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e4d\u0e32 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17 &#8211; \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23, accessed November 13, 2025, <a href=\"https:\/\/jeal.snru.ac.th\/Files\/Article\/1084-ArticleTextFile-20220625223308.pdf\">https:\/\/jeal.snru.ac.th\/Files\/Article\/1084-ArticleTextFile-20220625223308.pdf<\/a><\/li>\n\n\n\n<li>\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32 &#8211; \u0e18\u0e40\u0e19\u0e28 \u0e02\u0e33\u0e40\u0e01\u0e34\u0e14 &#8211; GotoKnow, accessed November 13, 2025, <a href=\"https:\/\/www.gotoknow.org\/posts\/514035\">https:\/\/www.gotoknow.org\/posts\/514035<\/a><\/li>\n\n\n\n<li>\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30 &#8230;, accessed November 13, 2025, <a href=\"https:\/\/so01.tci-thaijo.org\/index.php\/crrugds_ejournal\/article\/view\/79866\">https:\/\/so01.tci-thaijo.org\/index.php\/crrugds_ejournal\/article\/view\/79866<\/a><\/li>\n\n\n\n<li>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c 4.0 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 &#8211; \u0e2a\u0e1e\u0e1b.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u0e40\u0e02\u0e15 1, accessed November 13, 2025, <a href=\"https:\/\/www.phatthalung1.go.th\/%E0%B8%A8%E0%B8%B6%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8%E0%B8%81%E0%B9%8C-4-0-%E0%B9%80%E0%B8%9E%E0%B8%B4%E0%B9%88%E0%B8%A1%E0%B8%9E%E0%B8%B9%E0%B8%99%E0%B8%A8\/\">https:\/\/www.phatthalung1.go.th\/%E0%B8%A8%E0%B8%B6%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8%E0%B8%81%E0%B9%8C-4-0-%E0%B9%80%E0%B8%9E%E0%B8%B4%E0%B9%88%E0%B8%A1%E0%B8%9E%E0%B8%B9%E0%B8%99%E0%B8%A8\/<\/a><\/li>\n\n\n\n<li>\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567 &#8211; Flip eBook Pages 1-50 | AnyFlip, accessed November 13, 2025, <a href=\"https:\/\/anyflip.com\/lsyut\/jsmv\/basic\">https:\/\/anyflip.com\/lsyut\/jsmv\/basic<\/a><\/li>\n\n\n\n<li>\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32, accessed November 13, 2025, <a href=\"http:\/\/cmi.nfe.go.th\/nfecmiad\/myfile\/202105208C6ushj.pdf\">http:\/\/cmi.nfe.go.th\/nfecmiad\/myfile\/202105208C6ushj.pdf<\/a><\/li>\n\n\n\n<li>\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e1a\u0e1a PRT-RED Model \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e27\u0e22\u0e27\u0e07\u0e08\u0e23\u0e40\u0e14\u0e21\u0e21\u0e34\u0e48\u0e07 (PDCA) \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 &#8211; \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e10\u0e18\u0e23\u0e23\u0e21\u0e04\u0e38\u0e13 ::, accessed November 13, 2025, <a href=\"http:\/\/prt.ac.th\/_files_school\/52100509\/workteacher\/52100509_1_20210408-064654.pdf\">http:\/\/prt.ac.th\/_files_school\/52100509\/workteacher\/52100509_1_20210408-064654.pdf<\/a><\/li>\n\n\n\n<li>\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 PDCA \u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 (\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14) &#8211; GotoKnow, accessed November 13, 2025, <a href=\"https:\/\/www.gotoknow.org\/posts\/191135\">https:\/\/www.gotoknow.org\/posts\/191135<\/a><\/li>\n\n\n\n<li>PDCA \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23 ? \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 &#8211; HREX.asia, accessed November 13, 2025, <a href=\"https:\/\/th.hrnote.asia\/orgdevelopment\/what-is-pdca-210610\/\">https:\/\/th.hrnote.asia\/orgdevelopment\/what-is-pdca-210610\/<\/a><\/li>\n\n\n\n<li>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u00bb &#8211; Digital Learning Classroom, accessed November 13, 2025, <a href=\"https:\/\/krukob.com\/web\/sv-5\/\">https:\/\/krukob.com\/web\/sv-5\/<\/a><\/li>\n\n\n\n<li>Untitled &#8211; \u0e2a\u0e1e\u0e1b.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e02\u0e15 2, accessed November 13, 2025, <a href=\"https:\/\/surat2.go.th\/2021\/files\/com_news_school\/2024-07_1b4adcb5b0e7c94.pdf\">https:\/\/surat2.go.th\/2021\/files\/com_news_school\/2024-07_1b4adcb5b0e7c94.pdf<\/a><\/li>\n\n\n\n<li>\u0e43\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48 1.1 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u201c\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e1a\u0e1a\u0e0a\u0e35\u0e49\u0e41\u0e19\u0e30(Coaching Techniques)\u201d, accessed November 13, 2025, <a href=\"https:\/\/pound1983.wordpress.com\/wp-content\/uploads\/2012\/06\/utq-225.pdf\">https:\/\/pound1983.wordpress.com\/wp-content\/uploads\/2012\/06\/utq-225.pdf<\/a><\/li>\n\n\n\n<li>\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c, accessed November 13, 2025, <a href=\"https:\/\/www.nsw2.go.th\/wp\/wp-content\/uploads\/2023\/06\/ma-june.pdf\">https:\/\/www.nsw2.go.th\/wp\/wp-content\/uploads\/2023\/06\/ma-june.pdf<\/a><\/li>\n\n\n\n<li>\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01 (Active Learning), accessed November 13, 2025, <a href=\"https:\/\/www.sesaoskt.go.th\/wp-content\/uploads\/2023\/11\/2.-%E0%B9%80%E0%B8%A5%E0%B9%88%E0%B8%A1%E0%B8%A3%E0%B8%B9%E0%B8%9B%E0%B9%81%E0%B8%9A%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8-Active-Learning-%E0%B8%AA%E0%B8%9E%E0%B8%A1.%E0%B8%AA%E0%B8%B8%E0%B9%82%E0%B8%82%E0%B8%97%E0%B8%B1%E0%B8%A2.pdf\">https:\/\/www.sesaoskt.go.th\/wp-content\/uploads\/2023\/11\/2.-%E0%B9%80%E0%B8%A5%E0%B9%88%E0%B8%A1%E0%B8%A3%E0%B8%B9%E0%B8%9B%E0%B9%81%E0%B8%9A%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8-Active-Learning-%E0%B8%AA%E0%B8%9E%E0%B8%A1.%E0%B8%AA%E0%B8%B8%E0%B9%82%E0%B8%82%E0%B8%97%E0%B8%B1%E0%B8%A2.pdf<\/a><\/li>\n\n\n\n<li>PLC Leader \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 2 (\u0e2b\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48 2) \u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19, accessed November 13, 2025, <a href=\"https:\/\/www.starfishlabz.com\/blog\/666-plc-leader-%E0%B8%84%E0%B8%A3%E0%B8%B1%E0%B9%89%E0%B8%87%E0%B8%97%E0%B8%B5%E0%B9%88-2-%E0%B8%AB%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B8%97%E0%B8%B5%E0%B9%88-2-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8%E0%B9%80%E0%B8%9E%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%AA%E0%B8%A3%E0%B9%89%E0%B8%B2%E0%B8%87%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B9%80%E0%B8%82%E0%B9%89%E0%B8%A1%E0%B9%81%E0%B8%82%E0%B9%87%E0%B8%87%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%AA%E0%B8%96%E0%B8%B2%E0%B8%99%E0%B8%A8%E0%B8%B6%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B8%AA%E0%B8%B9%E0%B9%88%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%A2%E0%B8%B1%E0%B9%88%E0%B8%87%E0%B8%A2%E0%B8%B7%E0%B8%99\">https:\/\/www.starfishlabz.com\/blog\/666-plc-leader-%E0%B8%84%E0%B8%A3%E0%B8%B1%E0%B9%89%E0%B8%87%E0%B8%97%E0%B8%B5%E0%B9%88-2-%E0%B8%AB%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B8%97%E0%B8%B5%E0%B9%88-2-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%99%E0%B8%B4%E0%B9%80%E0%B8%97%E0%B8%A8%E0%B9%80%E0%B8%9E%E0%B8%B7%E0%B9%88%E0%B8%AD%E0%B8%AA%E0%B8%A3%E0%B9%89%E0%B8%B2%E0%B8%87%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B9%80%E0%B8%82%E0%B9%89%E0%B8%A1%E0%B9%81%E0%B8%82%E0%B9%87%E0%B8%87%E0%B8%82%E0%B8%AD%E0%B8%87%E0%B8%AA%E0%B8%96%E0%B8%B2%E0%B8%99%E0%B8%A8%E0%B8%B6%E0%B8%81%E0%B8%A9%E0%B8%B2%E0%B8%AA%E0%B8%B9%E0%B9%88%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%A2%E0%B8%B1%E0%B9%88%E0%B8%87%E0%B8%A2%E0%B8%B7%E0%B8%99<\/a><\/li>\n\n\n\n<li>\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e1a\u0e1a\u0e0a\u0e35\u0e49\u0e41\u0e19\u0e30\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e04\u0e34\u0e14 &#8211; phichituta, accessed November 13, 2025, <a href=\"https:\/\/phichituta.wordpress.com\/wp-content\/uploads\/2022\/08\/12-plan03.pdf\">https:\/\/phichituta.wordpress.com\/wp-content\/uploads\/2022\/08\/12-plan03.pdf<\/a><\/li>\n\n\n\n<li>\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 PLC : \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e2a\u0e1e\u0e1b &#8230;, accessed November 13, 2025, <a href=\"https:\/\/www.gotoknow.org\/posts\/628799\">https:\/\/www.gotoknow.org\/posts\/628799<\/a><\/li>\n\n\n\n<li>&#8220;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c&#8221; \u0e01\u0e25\u0e44\u0e01\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e38\u0e01 \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23 &#8211; \u0e44\u0e17\u0e22\u0e23\u0e31\u0e10, accessed November 13, 2025, <a href=\"https:\/\/www.thairath.co.th\/news\/local\/bangkok\/2868112\">https:\/\/www.thairath.co.th\/news\/local\/bangkok\/2868112<\/a><\/li>\n\n\n\n<li>4. \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 &#8211; \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c 2567, accessed November 13, 2025, <a href=\"https:\/\/sv1.esdc.go.th\/%E0%B8%AB%E0%B8%99%E0%B8%B2%E0%B9%81%E0%B8%A3%E0%B8%81\/%E0%B8%A3%E0%B8%B0%E0%B8%A2%E0%B8%B0%E0%B8%97-1-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%A2%E0%B8%A1%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B8%AD%E0%B8%99%E0%B9%80%E0%B8%82%E0%B8%B2%E0%B8%A3%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%92%E0%B8%99%E0%B8%B2\/4-%E0%B8%99%E0%B9%82%E0%B8%A2%E0%B8%9A%E0%B8%B2%E0%B8%A2%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%A8%E0%B8%81%E0%B8%A9%E0%B8%B2\">https:\/\/sv1.esdc.go.th\/%E0%B8%AB%E0%B8%99%E0%B8%B2%E0%B9%81%E0%B8%A3%E0%B8%81\/%E0%B8%A3%E0%B8%B0%E0%B8%A2%E0%B8%B0%E0%B8%97-1-%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%95%E0%B8%A3%E0%B8%A2%E0%B8%A1%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B8%9E%E0%B8%A3%E0%B8%AD%E0%B8%A1%E0%B8%81%E0%B8%AD%E0%B8%99%E0%B9%80%E0%B8%82%E0%B8%B2%E0%B8%A3%E0%B8%9A%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%92%E0%B8%99%E0%B8%B2\/4-%E0%B8%99%E0%B9%82%E0%B8%A2%E0%B8%9A%E0%B8%B2%E0%B8%A2%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%A8%E0%B8%81%E0%B8%A9%E0%B8%B2<\/a><\/li>\n\n\n\n<li>\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 The &#8211; ThaiJo, accessed November 13, 2025, <a href=\"https:\/\/so06.tci-thaijo.org\/index.php\/tmd\/article\/download\/279578\/187599\/1193438\">https:\/\/so06.tci-thaijo.org\/index.php\/tmd\/article\/download\/279578\/187599\/1193438<\/a><\/li>\n<\/ol>\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>","protected":false},"excerpt":{"rendered":"<p>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&#8221; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22<\/p>\n","protected":false},"author":1,"featured_media":15686,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[17,235],"tags":[236],"class_list":["post-15683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-supervision","tag-236"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &quot;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&quot; \u0e2a\u0e39\u0e48 &quot;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&quot; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 &#187;<\/title>\n<meta name=\"description\" content=\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &quot;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&quot; \u0e2a\u0e39\u0e48 &quot;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&quot; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/krukob.com\/web\/sv-48\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &quot;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&quot; \u0e2a\u0e39\u0e48 &quot;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&quot; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 &#187;\" \/>\n<meta property=\"og:description\" content=\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &quot;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&quot; \u0e2a\u0e39\u0e48 &quot;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&quot; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/krukob.com\/web\/sv-48\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Learning Classroom\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T11:59:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T07:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/krukob.com\/web\/wp-content\/uploads\/2025\/11\/ffgggk.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musicmankob\" \/>\n<meta name=\"twitter:site\" content=\"@musicmankob\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/\"},\"author\":{\"name\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"headline\":\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&#8221; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\",\"datePublished\":\"2025-11-13T11:59:38+00:00\",\"dateModified\":\"2025-11-14T07:33:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/\"},\"wordCount\":1640,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"image\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ffgggk.jpg?fit=1920%2C1080&ssl=1\",\"keywords\":[\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\"],\"articleSection\":[\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\",\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/\",\"name\":\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \\\"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\\\" \u0e2a\u0e39\u0e48 \\\"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\\\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 &#187;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ffgggk.jpg?fit=1920%2C1080&ssl=1\",\"datePublished\":\"2025-11-13T11:59:38+00:00\",\"dateModified\":\"2025-11-14T07:33:54+00:00\",\"description\":\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \\\"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\\\" \u0e2a\u0e39\u0e48 \\\"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\\\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ffgggk.jpg?fit=1920%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/ffgggk.jpg?fit=1920%2C1080&ssl=1\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/sv-48\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/krukob.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&#8221; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/\",\"name\":\"Digital Learning Classroom\",\"description\":\"Digital Learning Classroom\",\"publisher\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/krukob.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\",\"name\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"width\":500,\"height\":500,\"caption\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\"},\"logo\":{\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\" \u0e2a\u0e39\u0e48 \"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 &#187;","description":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\" \u0e2a\u0e39\u0e48 \"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/krukob.com\/web\/sv-48\/","og_locale":"en_US","og_type":"article","og_title":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\" \u0e2a\u0e39\u0e48 \"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 &#187;","og_description":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\" \u0e2a\u0e39\u0e48 \"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22","og_url":"https:\/\/krukob.com\/web\/sv-48\/","og_site_name":"Digital Learning Classroom","article_published_time":"2025-11-13T11:59:38+00:00","article_modified_time":"2025-11-14T07:33:54+00:00","og_image":[{"width":1920,"height":1080,"url":"http:\/\/krukob.com\/web\/wp-content\/uploads\/2025\/11\/ffgggk.jpg","type":"image\/jpeg"}],"author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","twitter_card":"summary_large_image","twitter_creator":"@musicmankob","twitter_site":"@musicmankob","twitter_misc":{"Written by":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/krukob.com\/web\/sv-48\/#article","isPartOf":{"@id":"https:\/\/krukob.com\/web\/sv-48\/"},"author":{"name":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"headline":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&#8221; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22","datePublished":"2025-11-13T11:59:38+00:00","dateModified":"2025-11-14T07:33:54+00:00","mainEntityOfPage":{"@id":"https:\/\/krukob.com\/web\/sv-48\/"},"wordCount":1640,"commentCount":0,"publisher":{"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"image":{"@id":"https:\/\/krukob.com\/web\/sv-48\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/11\/ffgggk.jpg?fit=1920%2C1080&ssl=1","keywords":["\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c"],"articleSection":["\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21","\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/krukob.com\/web\/sv-48\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/krukob.com\/web\/sv-48\/","url":"https:\/\/krukob.com\/web\/sv-48\/","name":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\" \u0e2a\u0e39\u0e48 \"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 &#187;","isPartOf":{"@id":"https:\/\/krukob.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/krukob.com\/web\/sv-48\/#primaryimage"},"image":{"@id":"https:\/\/krukob.com\/web\/sv-48\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/11\/ffgggk.jpg?fit=1920%2C1080&ssl=1","datePublished":"2025-11-13T11:59:38+00:00","dateModified":"2025-11-14T07:33:54+00:00","description":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 \"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\" \u0e2a\u0e39\u0e48 \"\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\" \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22","breadcrumb":{"@id":"https:\/\/krukob.com\/web\/sv-48\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/krukob.com\/web\/sv-48\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/krukob.com\/web\/sv-48\/#primaryimage","url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/11\/ffgggk.jpg?fit=1920%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/11\/ffgggk.jpg?fit=1920%2C1080&ssl=1","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/krukob.com\/web\/sv-48\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/krukob.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e21\u0e35\u0e44\u0e27\u0e49\u0e17\u0e33\u0e44\u0e21: \u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e1a\u0e17\u0e1a\u0e32\u0e17 &#8220;\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39&#8221; \u0e2a\u0e39\u0e48 &#8220;\u0e01\u0e25\u0e44\u0e01\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19&#8221; \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/krukob.com\/web\/#website","url":"https:\/\/krukob.com\/web\/","name":"Digital Learning Classroom","description":"Digital Learning Classroom","publisher":{"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/krukob.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6","name":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","url":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","contentUrl":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","width":500,"height":500,"caption":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14"},"logo":{"@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/11\/ffgggk.jpg?fit=1920%2C1080&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8LKk5-44X","jetpack-related-posts":[{"id":15306,"url":"https:\/\/krukob.com\/web\/sv-33\/","url_meta":{"origin":15683,"position":0},"title":"\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c: \u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"September 15, 2025","format":false,"excerpt":"\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c: \u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e34\u0e28\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e","rel":"","context":"In &quot;\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21&quot;","block_context":{"text":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21","link":"https:\/\/krukob.com\/web\/category\/article\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv22.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv22.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv22.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv22.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv22.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15318,"url":"https:\/\/krukob.com\/web\/sv-34\/","url_meta":{"origin":15683,"position":1},"title":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e19\u0e34\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07: \u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01\u0e1d\u0e31\u0e07 Growth Mindset \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e23\u0e39\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"September 19, 2025","format":false,"excerpt":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e19\u0e34\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07: \u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01\u0e1d\u0e31\u0e07 Growth Mindset \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e23\u0e39\u0e40\u0e0a\u0e34\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","rel":"","context":"In &quot;\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21&quot;","block_context":{"text":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21","link":"https:\/\/krukob.com\/web\/category\/article\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/cccccc.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/cccccc.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/cccccc.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/cccccc.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/cccccc.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15043,"url":"https:\/\/krukob.com\/web\/sv-22\/","url_meta":{"origin":15683,"position":2},"title":"\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e39\u0e48\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 (R2R):\u00a0\u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"June 29, 2025","format":false,"excerpt":"\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e39\u0e48\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 (R2R):\u00a0\u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e43\u0e19\u0e22\u0e38\u0e04\u0e17\u0e35\u0e48\u0e42\u0e25\u0e01\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19 \u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u00a0\u201c\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u201d\u00a0\u0e44\u0e14\u0e49\u0e16\u0e39\u0e01\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u00a0\u201c\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u201d (Academic Leader)\u00a0\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e49\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u00a0\"\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2a\u0e39\u0e48\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 (Routine to Research: R2R)\"\u00a0\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e04\u0e13\u0e30\u0e28\u0e36\u0e01\u0e29\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e34\u0e25\u0e1b\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30 \u0e2a\u0e1e\u0e10. \u0e08\u0e36\u0e07\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e38\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e17\u0e35\u0e48\u0e21\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07 \u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49\u0e08\u0e30\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e22\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u00a0R2R\u00a0\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e2a\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e19\u0e34\u0e22\u0e32\u0e21\u0e43\u0e2b\u0e21\u0e48\u00a010\u00a0\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c: \u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e08\u0e23\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e44\u0e14\u0e49\u0e09\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e01.\u0e04.\u0e28.) \u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e22\u0e49\u0e33\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e16\u0e2d\u0e14\u0e23\u0e2b\u0e31\u0e2a\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u00a010\u00a0\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e36\u0e01\u0e0b\u0e36\u0e49\u0e07 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 (Researcher):\u00a0\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u00a0R2R\u00a0\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d \u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39 (Teacher\/Instructor):\u00a0\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e41\u0e1a\u0e1a\u00a0Active Learning,\u00a0\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23 (Innovator):\u00a0\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e43\u0e2b\u0e21\u0e48 \u0e46 \u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e19\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a (Designer):\u00a0\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u00a0\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 (Differentiated Supervision)\u00a0\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e23\u0e39\u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e19\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e19\u0e34\u0e40\u0e17\u0e28\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e04\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14 (Peer\/Friend):\u00a0\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1a\u0e19\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e44\u0e27\u0e49\u0e27\u0e32\u0e07\u0e43\u0e08\u2026","rel":"","context":"In &quot;\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21&quot;","block_context":{"text":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21","link":"https:\/\/krukob.com\/web\/category\/article\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv46.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv46.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv46.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv46.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv46.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15015,"url":"https:\/\/krukob.com\/web\/sv-18\/","url_meta":{"origin":15683,"position":3},"title":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e17\u0e22: \u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"June 22, 2025","format":false,"excerpt":"\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e44\u0e17\u0e22: \u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e48\u0e27\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e14\u0e49\u0e27\u0e22\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e17\u0e22\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e40\u0e1b\u0e47\u0e19 \"\u0e04\u0e23\u0e39\u0e02\u0e2d\u0e07\u0e04\u0e23\u0e39\" \u0e41\u0e15\u0e48\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e17\u0e1a\u0e32\u0e17 - \u0e40\u0e14\u0e34\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e2a\u0e39\u0e07 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e41\u0e15\u0e48\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e32\u0e15\u0e23\u0e27\u0e08\u0e07\u0e32\u0e19 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e19\u0e34\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19 - \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e23\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e07\u0e32\u0e19\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e19\u0e34\u0e40\u0e17\u0e28\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e44\u0e14\u0e49 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e14\u0e41\u0e04\u0e25\u0e19\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 - \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e02\u0e32\u0e14\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e2d\u0e22\u0e39\u0e48\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e27\u0e48\u0e32\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 1,000 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e44\u0e14\u0e49\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35 4 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e2b\u0e25\u0e31\u0e01: \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e07 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e39\u0e48\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e41\u0e17\u0e23\u0e47\u0e01 1: \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e08\u0e32\u0e01\u0e04\u0e23\u0e39 (\u0e40\u0e14\u0e34\u0e21) -\u2026","rel":"","context":"In &quot;\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21&quot;","block_context":{"text":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21","link":"https:\/\/krukob.com\/web\/category\/article\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv55.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv55.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv55.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv55.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/06\/sv55.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":15295,"url":"https:\/\/krukob.com\/web\/sv-32\/","url_meta":{"origin":15683,"position":4},"title":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e22\u0e38\u0e04 AI: \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e39\u0e48\u0e2a\u0e16\u0e32\u0e1b\u0e19\u0e34\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"September 14, 2025","format":false,"excerpt":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e22\u0e38\u0e04 AI: \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e23\u0e39\u0e1b\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e39\u0e48\u0e2a\u0e16\u0e32\u0e1b\u0e19\u0e34\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49","rel":"","context":"In &quot;AI&quot;","block_context":{"text":"AI","link":"https:\/\/krukob.com\/web\/category\/ai-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2025\/09\/sv.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":13517,"url":"https:\/\/krukob.com\/web\/sv-3\/","url_meta":{"origin":15683,"position":5},"title":"\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e40\u0e0a\u0e34\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"February 20, 2024","format":false,"excerpt":"\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e40\u0e0a\u0e34\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c","rel":"","context":"In &quot;\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c&quot;","block_context":{"text":"\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e34\u0e40\u0e17\u0e28\u0e01\u0e4c","link":"https:\/\/krukob.com\/web\/category\/supervision\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2024\/02\/image-18.png?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2024\/02\/image-18.png?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2024\/02\/image-18.png?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2024\/02\/image-18.png?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/15683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/comments?post=15683"}],"version-history":[{"count":2,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/15683\/revisions"}],"predecessor-version":[{"id":15688,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/15683\/revisions\/15688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media\/15686"}],"wp:attachment":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media?parent=15683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/categories?post=15683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/tags?post=15683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}