{"id":3279,"date":"2020-03-03T12:32:00","date_gmt":"2020-03-03T05:32:00","guid":{"rendered":"http:\/\/krukob.com\/web\/?p=3279"},"modified":"2020-03-03T13:03:15","modified_gmt":"2020-03-03T06:03:15","slug":"1-124","status":"publish","type":"post","link":"https:\/\/krukob.com\/web\/1-124\/","title":{"rendered":"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19"},"content":{"rendered":"<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>\n<p class=\"wp-block-paragraph\"><strong>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/strong> \u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 2 \u0e01\u0e25\u0e38\u0e48\u0e21 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e14\u0e49\u0e27\u0e22 <strong><a rel=\"noreferrer noopener\" aria-label=\"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (\u0e28\u0e18 0206.3\/ 0635 ) (opens in a new tab)\" href=\"https:\/\/qrgo.page.link\/WsNk2\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (\u0e28\u0e18 0206.3\/ 0635 )<\/a><\/strong> \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/li><li>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a <strong><a rel=\"noreferrer noopener\" aria-label=\"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e27\u00a06\/2562)\u00a0 (opens in a new tab)\" href=\"https:\/\/qrgo.page.link\/\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e27\u00a06\/2562)\u00a0<\/a><\/strong> \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/li><\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/qrgo.page.link\/WsNk2\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (\u0e28\u0e18 0206.3\/ 0635 )<\/a><\/strong> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e30 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u00a0(\u0e01.\u0e04.\u0e28.) \u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e21\u0e35\u0e21\u0e15\u0e34\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u00a0\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e15\u0e32\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 (\u0e28\u0e18 0206.3\/\u0e27 21)\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e42\u0e14\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e2a\u0e2d\u0e19\u0e15\u0e32\u0e21\u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e2d\u0e19 \u0e15\u0e32\u0e21\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 (\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22 1)<\/strong>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19<\/strong>&nbsp;\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e2a\u0e2d\u0e19\u0e15\u0e32\u0e21\u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e2d\u0e19 \u0e07\u0e32\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e38\u0e14\u0e40\u0e19\u0e49\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>1.1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e2a\u0e2d\u0e19\u0e15\u0e32\u0e21\u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e2d\u0e19&nbsp;<\/strong>\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\/\u0e2a\u0e32\u0e02\u0e32\/\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>1.2 \u0e07\u0e32\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&nbsp;<\/strong>\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e07\u0e32\u0e19\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong>1.3 \u0e07\u0e32\u0e19\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e38\u0e14\u0e40\u0e19\u0e49\u0e19<\/strong>\u00a0\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e38\u0e14\u0e40\u0e19\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39<\/strong>\u00a0\u0e17\u0e35\u0e48\u0e08\u0e30\u0e02\u0e2d\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e2a\u0e2d\u0e19\u0e15\u0e32\u0e21\u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e2d\u0e19 \u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d 1.1 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/strong><strong><\/strong><\/td><td><strong>\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e2a\u0e2d\u0e19\u0e15\u0e32\u0e21\u0e15\u0e32\u0e23\u0e32\u0e07\u0e2a\u0e2d\u0e19<\/strong><strong><\/strong><\/td><\/tr><tr><td>1. \u0e1b\u0e10\u0e21\u0e27\u0e31\u0e22<\/td><td>\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 6 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\/\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c<\/td><\/tr><tr><td>2. \u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e23\u0e27\u0e21\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e2b\u0e23\u0e37\u0e2d&nbsp;<br>&nbsp;&nbsp;&nbsp;&nbsp;\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e27\u0e21)<\/td><td>\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 12 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\/\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c<\/td><\/tr><tr><td>3. \u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e23\u0e27\u0e21\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e2b\u0e23\u0e37\u0e2d&nbsp;<br>&nbsp;&nbsp;&nbsp;&nbsp;\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e27\u0e21)<\/td><td>\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 12 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\/\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c<\/td><\/tr><tr><td>4. \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u00a0\u00a0\u00a0<br>\u00a04.1 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u00a0\u00a0\u00a0\u00a0\u00a0<br>4.2 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e32\u0e0a\u0e1b\u0e23\u0e30\u0e0b\u0e32\u0e19\u0e38\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c<\/td><td><br>\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 6 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\/\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c<br>\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 12 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\/\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e25\u0e30<strong>\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u00a0(\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22 2)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19 3 \u0e14\u0e49\u0e32\u0e19 13 \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<\/strong><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.1 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.2 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.2.1 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.2.2 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\/\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 (IEP)\/\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25 (IIP)\/\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.2.3 \u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.2.4 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.3 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.4 \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;1.5 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;<\/strong><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;2. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;2.1 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;2.2 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;2.3 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e0a\u0e32&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>3. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;3.1 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a03.2 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<\/strong><\/td><td><strong>\u0e04\u0e23\u0e39\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23<\/strong><strong><\/strong><\/td><td><strong>\u0e04\u0e23\u0e39\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29<\/strong><strong><\/strong><\/td><td><strong>\u0e04\u0e23\u0e39\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d<\/strong><strong><\/strong><\/td><td><strong>\u0e04\u0e23\u0e39\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1e\u0e34\u0e40\u0e28\u0e29<\/strong><strong><\/strong><\/td><\/tr><tr><td>1.&nbsp;\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19(8&nbsp;\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14)<\/td><td>\u0e17\u0e38\u0e01\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<br>\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32<br>\u0e23\u0e30\u0e14\u0e31\u0e1a&nbsp;2<\/td><td>\u0e17\u0e38\u0e01\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<br>\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a&nbsp;3<\/td><td>\u0e17\u0e38\u0e01\u0e15\u0e31\u0e27\u0e1a\u0e48\u0e07\u0e0a\u0e35\u0e49&nbsp;<br>\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32&nbsp;<br>\u0e23\u0e30\u0e14\u0e31\u0e1a&nbsp;4<\/td><td>\u0e17\u0e38\u0e01\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<br>\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a&nbsp;5<\/td><\/tr><tr><td>2.\u00a0\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u00a0(3\u00a0\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14)<br>3. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (2 \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14)<\/td><td>\u0e14\u0e49\u0e32\u0e19&nbsp;2&nbsp;\u0e41\u0e25\u0e30&nbsp;3<br>&nbsp;\u0e41\u0e15\u0e48\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a&nbsp;2&nbsp;\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32<br>1&nbsp;\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<\/td><td>\u0e14\u0e49\u0e32\u0e19&nbsp;2&nbsp;\u0e41\u0e25\u0e30&nbsp;3&nbsp;<br>\u0e17\u0e31\u0e49\u0e07&nbsp;2&nbsp;\u0e14\u0e49\u0e32\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49<br>\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a&nbsp;2&nbsp;<br>\u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27<br>\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32&nbsp;3&nbsp;\u0e15\u0e31\u0e27\u0e1a\u0e48\u0e07\u0e0a\u0e35\u0e49<\/td><td>\u0e14\u0e49\u0e32\u0e19&nbsp;2&nbsp;\u0e41\u0e25\u0e30&nbsp;3&nbsp;<br>\u0e17\u0e31\u0e49\u0e07&nbsp;2&nbsp;\u0e14\u0e49\u0e32\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a 3&nbsp;<br>\u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27<br>\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32&nbsp;<br>3&nbsp;\u0e15\u0e31\u0e27\u0e1a\u0e48\u0e07\u0e0a\u0e35\u0e49<\/td><td>\u0e14\u0e49\u0e32\u0e19&nbsp;2&nbsp;\u0e41\u0e25\u0e30&nbsp;3&nbsp;<br>\u0e17\u0e31\u0e49\u0e07&nbsp;2&nbsp;\u0e14\u0e49\u0e32\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 \u0e23\u0e30\u0e14\u0e31\u0e1a 4<br>\u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27<br>\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32&nbsp;<br>3&nbsp;\u0e15\u0e31\u0e27\u0e1a\u0e48\u0e07\u0e0a\u0e35\u0e49<\/td><\/tr><tr><td>4. \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e19\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32<br>\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 75<\/td><td>\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e04\u0e19\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32<br>\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 80<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong><a rel=\"noreferrer noopener\" aria-label=\"\u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 (opens in a new tab)\" href=\"https:\/\/drive.google.com\/file\/d\/1ft9OQPXB0z1IowJD2P5XZk2wPDBeDH5U\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u0e44\u0e1f\u0e25\u0e4c <a rel=\"noreferrer noopener\" aria-label=\"\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (opens in a new tab)\" href=\"https:\/\/drive.google.com\/file\/d\/1ft9OQPXB0z1IowJD2P5XZk2wPDBeDH5U\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/qrgo.page.link\/\" target=\"_blank\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e27\u00a06\/2562)\u00a0<\/a><\/strong> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1c\u0e25\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u00a0\u0e1e\u0e28.\u00a02562\u00a0\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u00a01\u00a0(\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a01\u00a0\u0e15\u0e38\u0e25\u0e32\u0e04\u0e21\u00a02561\u00a0\u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a031\u00a0\u0e21\u0e35\u0e19\u0e32\u0e04\u0e21\u00a02562) \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b (<a rel=\"noreferrer noopener\" aria-label=\"\u0e2720\/2561 (opens in a new tab)\" href=\"https:\/\/drive.google.com\/file\/d\/1gWMr37oQYvMa2Yr8BHsMcOxXxC-8CQCs\/view?usp=sharing\" target=\"_blank\">\u0e2720\/2561<\/a> \u0e41\u0e25\u0e30 <a rel=\"noreferrer noopener\" aria-label=\"\u0e276\/2562 (opens in a new tab)\" href=\"https:\/\/qrgo.page.link\/G1HBT\" target=\"_blank\">\u0e276\/2562<\/a>)\u00a0\u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c 5 \u0e02\u0e49\u0e2d \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1856\" height=\"1196\" data-attachment-id=\"3286\" data-permalink=\"https:\/\/krukob.com\/web\/1-124\/image-2-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?fit=1856%2C1196&amp;ssl=1\" data-orig-size=\"1856,1196\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?fit=800%2C516&amp;ssl=1\" src=\"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?fit=800%2C516\" alt=\"\" class=\"wp-image-3286\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?w=1856&amp;ssl=1 1856w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?resize=300%2C193&amp;ssl=1 300w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?resize=1024%2C660&amp;ssl=1 1024w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?resize=768%2C495&amp;ssl=1 768w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?resize=1536%2C990&amp;ssl=1 1536w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-2.png?w=1600 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1b\u0e35\u0e25\u0e30 2 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e15\u0e32\u0e21\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u00a0<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1856\" height=\"1194\" data-attachment-id=\"3287\" data-permalink=\"https:\/\/krukob.com\/web\/1-124\/image-3-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?fit=1856%2C1194&amp;ssl=1\" data-orig-size=\"1856,1194\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?fit=800%2C515&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?fit=800%2C515\" alt=\"\" class=\"wp-image-3287\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?w=1856&amp;ssl=1 1856w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?resize=300%2C193&amp;ssl=1 300w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?resize=1024%2C659&amp;ssl=1 1024w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?resize=768%2C494&amp;ssl=1 768w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?resize=1536%2C988&amp;ssl=1 1536w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-3.png?w=1600 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e30\u0e41\u0e19\u0e19\u0e23\u0e27\u0e21 100 \u0e04\u0e30\u0e41\u0e19\u0e19\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 \u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48 1 (70 \u0e04\u0e30\u0e41\u0e19\u0e19) \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48 2 (30 \u0e04\u0e30\u0e41\u0e19\u0e19) \u0e14\u0e31\u0e07\u0e20\u0e32\u0e1e<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2088\" height=\"1214\" data-attachment-id=\"3288\" data-permalink=\"https:\/\/krukob.com\/web\/1-124\/image-4-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?fit=2088%2C1214&amp;ssl=1\" data-orig-size=\"2088,1214\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-4\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?fit=800%2C465&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?fit=800%2C465\" alt=\"\" class=\"wp-image-3288\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?w=2088&amp;ssl=1 2088w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?resize=300%2C174&amp;ssl=1 300w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?resize=1024%2C595&amp;ssl=1 1024w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?resize=768%2C447&amp;ssl=1 768w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?resize=1536%2C893&amp;ssl=1 1536w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?resize=2048%2C1191&amp;ssl=1 2048w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-4.png?w=1600 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 2 \u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e23\u0e27\u0e21 100 \u0e04\u0e30\u0e41\u0e19\u0e19 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"has-text-color has-vivid-red-color wp-block-paragraph\"><strong>\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48 1 <\/strong>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e15\u0e32\u0e21\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 5 \u0e23\u0e30\u0e14\u0e31\u0e1a \u0e08\u0e32\u0e01\u0e19\u0e49\u0e2d\u0e22\u0e44\u0e1b\u0e2b\u0e32\u0e21\u0e32\u0e01 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a 1 -5 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"has-text-color has-vivid-red-color wp-block-paragraph\"><strong>\u00a0\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 (70\u00a0\u0e04\u0e30\u0e41\u0e19\u0e19)<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e30\u0e41\u0e19\u0e19<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\u0e04\u0e30\u0e41\u0e19\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u00a0=\u00a0\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u00a0x\u00a0\u0e04\u0e48\u0e32\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 4 \u0e14\u0e49\u0e32\u0e19\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u00a01<\/strong>\u00a0\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u00a0(\u0e04\u0e30\u0e41\u0e19\u0e19\u0e40\u0e15\u0e47\u0e21\u00a045\u00a0\u0e04\u0e30\u0e41\u0e19\u0e19)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u00a02\u00a0<\/strong>\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u00a0(\u0e04\u0e30\u0e41\u0e19\u0e19\u0e40\u0e15\u0e47\u0e21 10 \u0e04\u0e30\u0e41\u0e19\u0e19)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u00a03<\/strong>\u00a0\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u00a0(\u0e04\u0e30\u0e41\u0e19\u0e19\u0e40\u0e15\u0e47\u0e21 10 \u0e04\u0e30\u0e41\u0e19\u0e19)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u00a04<\/strong>\u00a0\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22(\u0e04\u0e30\u0e41\u0e19\u0e19\u0e40\u0e15\u0e47\u0e21\u00a05\u00a0\u0e04\u0e30\u0e41\u0e19\u0e19)<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1704\" height=\"784\" data-attachment-id=\"3289\" data-permalink=\"https:\/\/krukob.com\/web\/1-124\/image-5-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?fit=1704%2C784&amp;ssl=1\" data-orig-size=\"1704,784\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-5\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?fit=800%2C368&amp;ssl=1\" src=\"https:\/\/i1.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?fit=800%2C368\" alt=\"\" class=\"wp-image-3289\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?w=1704&amp;ssl=1 1704w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?resize=300%2C138&amp;ssl=1 300w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?resize=1024%2C471&amp;ssl=1 1024w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?resize=768%2C353&amp;ssl=1 768w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?resize=1536%2C707&amp;ssl=1 1536w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-5.png?w=1600 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption><strong><a href=\"https:\/\/qrgo.page.link\/hPTfw\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"https:\/\/qrgo.page.link\/hPTfw (opens in a new tab)\">https:\/\/qrgo.page.link\/hPTfw<\/a><\/strong><br><strong><a href=\"https:\/\/qrgo.page.link\/Vne6Z\">https:\/\/qrgo.page.link\/Vne6Z<\/a><\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>1.1 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/strong><\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e1c\u0e25\u0e44\u0e1b\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e42\u0e14\u0e22\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u00a0<\/li><li>\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19<\/li><li>\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/li><li> \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.2 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>1.2.1 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/strong><\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e19\u0e33\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3\u00a0\u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2\u00a0\u0e21\u0e35\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\/\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li> \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u00a0<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/li><li> \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u00a0<\/li><\/ol>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>1.2.2 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\/\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25(IEP)\/<br>\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25 (IIP)\/\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c<\/strong><\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5\u00a0\u0e21\u0e35\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e19\u0e33\u0e1c\u0e25\u0e21\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4\u00a0\u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22<strong>\u0e19<\/strong><\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3\u00a0\u0e21\u0e35\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2f\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e04\u0e23\u0e1a\u0e16\u0e49\u0e27\u0e19\u0e15\u0e32\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e15\u0e49\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2f\u00a0\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1\u00a0\u0e21\u0e35\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/li><li>\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2f3) \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1c\u0e25\u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e2d\u0e19<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>1.2.3 \u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/strong><\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e1c\u0e25 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e08\u0e38\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e25\u0e30\u0e40\u0e19\u0e49\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u00a0active learning<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/li><li>\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>1.2.4.1 \u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5\u00a0\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 70 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4\u00a0\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 65 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3\u00a0\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 60 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2\u00a0\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 55 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19 \u0e21\u0e35\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1\u00a0\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 50 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19 \u0e21\u0e35\u0e1c\u0e25\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e1c\u0e25\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\/\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>1.2.4.2 \u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 90 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 85 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 80 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 75 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 70 \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e19 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e48\u0e32\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21<\/li><li>\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30 \u0e17\u0e35\u0e48\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e01\u0e19\u0e01\u0e25\u0e32\u0e07<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.3 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e33\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e17\u0e35\u0e48\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e25\u0e49\u0e27\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e25\u0e30\u00a0\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u00a0<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.4\u00a0\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e15\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a\u00a01\u00a0\u0e21\u0e35\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e34\u0e19\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u00a0\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u00a0\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e27\u0e31\u0e14\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u00a0<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u00a0\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1.5 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e1a\u0e17\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e2f<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e2f<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.1 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e23\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e34\u0e14\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e41\u0e25\u0e30\u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e0a\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1a\u0e1a\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e44\u0e14\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21\u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e2d\u0e31\u0e19\u0e1e\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49 \u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e0a\u0e32\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e04\u0e34\u0e14 \u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e0a\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e0a\u0e32 \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e15\u0e48\u0e2d \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e0a\u0e32<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e2a\u0e20\u0e32\u0e1e\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<\/li><li>\u0e1b\u0e49\u0e32\u0e22\u0e41\u0e2a\u0e14\u0e07 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e1b\u0e49\u0e32\u0e22\u0e19\u0e34\u0e40\u0e17\u0e28\u0e1b\u0e49\u0e32\u0e22\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e193) \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28<\/li><li>\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e34\u0e0a\u0e32<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30 \u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2.2 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e2b\u0e47\u0e19\u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\/\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\/\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u00a0<\/li><li>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\/\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e39\u0e41\u0e25 \u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u00a0<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22<\/li><li>\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.1 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e32\u0e21\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e21\u0e35\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e17\u0e31\u0e01\u0e29\u0e30 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30 \u0e2a\u0e20\u0e32\u0e1e\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e41\u0e1f\u0e49\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3.2 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e1a\u0e1a\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e21\u0e32\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e23\u0e39<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e04\u0e23\u0e39\u00a0<\/li><li>\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e21\u0e32\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 4) \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u00a0<\/li><li> \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. \u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 5 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35\u0e44\u0e14\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 4 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22 \u0e21\u0e35\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e43\u0e2a \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e44\u0e14\u0e49<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 3 \u0e21\u0e35\u0e1c\u0e25\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22 \u0e44\u0e14\u0e49\u0e1c\u0e25\u0e14\u0e35 \u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 2 \u0e21\u0e35\u0e1c\u0e25\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e41\u0e1a\u0e1a\u0e41\u0e1c\u0e19\u00a0<\/td><\/tr><tr><td>\u0e23\u0e30\u0e14\u0e31\u0e1a 1 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e07\u0e32\u0e19\u00a0<\/li><li>\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u00a0<\/li><li>\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u00a0<\/li><li>\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07<\/li><\/ol>\n\n\n\n<p class=\"has-text-color has-vivid-red-color wp-block-paragraph\">\u0e2d\u0e07\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48 2 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e34\u0e19\u0e31\u0e22 \u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30<br> \u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 6 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e25\u0e30 5 \u0e04\u0e30\u0e41\u0e19\u0e19 \u0e23\u0e27\u0e21 30 \u0e04\u0e30\u0e41\u0e19\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e37\u0e48\u0e19\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e19\u0e15\u0e32\u0e21\u0e2a\u0e20\u0e32\u0e1e\u0e08\u0e23\u0e34\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19<\/p>\n\n\n\n<p class=\"has-text-color has-vivid-red-color wp-block-paragraph\"><strong>\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e34\u0e19\u0e31\u0e22 \u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (30 \u0e04\u0e30\u0e41\u0e19\u0e19)<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"\"><tbody><tr><td><strong>\u0e17\u0e35\u0e48<\/strong><\/td><td><strong>\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19<\/strong><\/td><td><strong>\u0e04\u0e30\u0e41\u0e19\u0e19\u0e40\u0e15\u0e47\u0e21<\/strong><\/td><td><strong>\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e15\u0e19\u0e40\u0e2d\u0e07<\/strong><\/td><td><strong>\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e32<\/strong><\/td><\/tr><tr><td><strong>1<\/strong><\/td><td>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e22\u0e4c \u0e2a\u0e38\u0e08\u0e23\u0e34\u0e15 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e27\u0e21 \u0e44\u0e21\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e34\u0e19\u0e22\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e0a\u0e49\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c<\/td><td>5<\/td><td>&nbsp;<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>2<\/strong><\/td><td>\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e32<\/td><td>5<\/td><td>&nbsp;<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>3<\/strong><\/td><td>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e23\u0e34\u0e22\u0e30 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e30 \u0e15\u0e23\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e27\u0e25\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e40\u0e27\u0e25\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23&nbsp;&nbsp;<\/td><td>5<\/td><td>&nbsp;<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>4<\/strong><\/td><td>\u0e01\u0e32\u0e23\u0e21\u0e35\u0e08\u0e34\u0e15\u0e2a\u0e33\u0e19\u0e36\u0e01\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e21\u0e38\u0e48\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34<\/td><td>5<\/td><td>&nbsp;<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>5<\/strong><\/td><td>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e41\u0e25\u0e30\u0e08\u0e23\u0e23\u0e22\u0e32\u0e1a\u0e23\u0e23\u0e13\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e<\/td><td>5<\/td><td>&nbsp;<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>6<\/strong><\/td><td>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21<\/td><td>5<\/td><td>&nbsp;<\/td><td>&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e44\u0e1f\u0e25\u0e4c  <a style=\"font-weight: bold;\" href=\"https:\/\/drive.google.com\/file\/d\/1C1ohslhAKm1bxSyCH_aks8P3FnayFHa5\/view?fbclid=IwAR3Do1MHa58hPdmPFnwb5Sv9qsmVAAFuM345-9UBGdZYVqXm2r8SnzcyIfY\">\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/a> (Docx)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong><a rel=\"noreferrer noopener\" aria-label=\"\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 (opens in a new tab)\" href=\"https:\/\/drive.google.com\/file\/d\/1C1ohslhAKm1bxSyCH_aks8P3FnayFHa5\/view?fbclid=IwAR3Do1MHa58hPdmPFnwb5Sv9qsmVAAFuM345-9UBGdZYVqXm2r8SnzcyIfY\" target=\"_blank\">\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e23\u0e38\u0e1b\u0e43\u0e19\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e43\u0e19\u0e17\u0e38\u0e01 \u0e46 \u0e20\u0e32\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e04\u0e23\u0e39 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e21\u0e35\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19 3 \u0e14\u0e49\u0e32\u0e19 13 \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0e\u0e0a\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e38\u0e1b \u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e20\u0e32\u0e1e \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2268\" height=\"1208\" data-attachment-id=\"3301\" data-permalink=\"https:\/\/krukob.com\/web\/1-124\/image-6-3\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?fit=2268%2C1208&amp;ssl=1\" data-orig-size=\"2268,1208\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?fit=800%2C426&amp;ssl=1\" src=\"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?fit=800%2C426\" alt=\"\" class=\"wp-image-3301\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?w=2268&amp;ssl=1 2268w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?resize=300%2C160&amp;ssl=1 300w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?resize=1024%2C545&amp;ssl=1 1024w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?resize=768%2C409&amp;ssl=1 768w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?resize=1536%2C818&amp;ssl=1 1536w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?resize=2048%2C1091&amp;ssl=1 2048w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/image-6.png?w=1600 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong><a rel=\"noreferrer noopener\" aria-label=\"\u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 (opens in a new tab)\" href=\"https:\/\/drive.google.com\/file\/d\/1ft9OQPXB0z1IowJD2P5XZk2wPDBeDH5U\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u0e15\u0e31\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e1f\u0e25\u0e4c <a rel=\"noreferrer noopener\" aria-label=\"\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (opens in a new tab)\" href=\"https:\/\/drive.google.com\/file\/d\/1ft9OQPXB0z1IowJD2P5XZk2wPDBeDH5U\/view?usp=sharing\" target=\"_blank\">\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/a> \u0e2721\/2560<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e44\u0e1f\u0e25\u0e4c  <a style=\"font-weight: bold;\" href=\"https:\/\/drive.google.com\/file\/d\/1C1ohslhAKm1bxSyCH_aks8P3FnayFHa5\/view?fbclid=IwAR3Do1MHa58hPdmPFnwb5Sv9qsmVAAFuM345-9UBGdZYVqXm2r8SnzcyIfY\">\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/a> (Docx)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong><a rel=\"noreferrer noopener\" aria-label=\"\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 (opens in a new tab)\" href=\"https:\/\/drive.google.com\/file\/d\/1C1ohslhAKm1bxSyCH_aks8P3FnayFHa5\/view?fbclid=IwAR3Do1MHa58hPdmPFnwb5Sv9qsmVAAFuM345-9UBGdZYVqXm2r8SnzcyIfY\" target=\"_blank\">\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19<\/a><\/strong> \u0e276\/2562<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e25\u0e2d\u0e07\u0e19\u0e33\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e19\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e2b\u0e32\u0e01\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 Add Line \u0e21\u0e32\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48 Musicmankob<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-medium\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" data-attachment-id=\"3207\" data-permalink=\"https:\/\/krukob.com\/web\/1-123\/s__20553751\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?fit=900%2C900&amp;ssl=1\" data-orig-size=\"900,900\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"S__20553751\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?fit=800%2C800&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?resize=300%2C300\" alt=\"\" class=\"wp-image-3207\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?resize=50%2C50&amp;ssl=1 50w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/02\/S__20553751.jpg?w=900&amp;ssl=1 900w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14<\/p>\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>","protected":false},"excerpt":{"rendered":"<p>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 2 \u0e01\u0e25\u0e38\u0e48\u0e21 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (\u0e28\u0e18 0206.3\/ 0635 ) \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<br \/>\n\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e27 6\/2562)  \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/p>\n","protected":false},"author":1,"featured_media":3299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46,71],"tags":[73,81,82],"class_list":["post-3279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-academia","category-academicstanding","tag-73","tag-81","tag-82"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 &#187;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/krukob.com\/web\/1-124\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 &#187;\" \/>\n<meta property=\"og:description\" content=\"\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 2 \u0e01\u0e25\u0e38\u0e48\u0e21 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d \u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (\u0e28\u0e18 0206.3\/ 0635 ) \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e27 6\/2562) \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\" \/>\n<meta property=\"og:url\" content=\"https:\/\/krukob.com\/web\/1-124\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Learning Classroom\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-03T05:32:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-03T06:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00153.jpg?fit=1320%2C741&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"741\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musicmankob\" \/>\n<meta name=\"twitter:site\" content=\"@musicmankob\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/\"},\"author\":{\"name\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"headline\":\"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\",\"datePublished\":\"2020-03-03T05:32:00+00:00\",\"dateModified\":\"2020-03-03T06:03:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/\"},\"wordCount\":397,\"publisher\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"image\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/00153.jpg?fit=1320%2C741&ssl=1\",\"keywords\":[\"\u0e2721\",\"\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\",\"\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\"],\"articleSection\":[\"\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\",\"\u0e27\u0e34\u0e17\u0e22\u0e30\u0e10\u0e32\u0e19\u0e30\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/\",\"name\":\"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 &#187;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/00153.jpg?fit=1320%2C741&ssl=1\",\"datePublished\":\"2020-03-03T05:32:00+00:00\",\"dateModified\":\"2020-03-03T06:03:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/00153.jpg?fit=1320%2C741&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/00153.jpg?fit=1320%2C741&ssl=1\",\"width\":1320,\"height\":741},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/1-124\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/krukob.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/\",\"name\":\"Digital Learning Classroom\",\"description\":\"Digital Learning Classroom\",\"publisher\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/krukob.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\",\"name\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"width\":500,\"height\":500,\"caption\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\"},\"logo\":{\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 &#187;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/krukob.com\/web\/1-124\/","og_locale":"en_US","og_type":"article","og_title":"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 &#187;","og_description":"\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19 2 \u0e01\u0e25\u0e38\u0e48\u0e21 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e37\u0e2d \u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 (\u0e28\u0e18 0206.3\/ 0635 ) \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e21\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e27 6\/2562) \u0e17\u0e38\u0e01\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32","og_url":"https:\/\/krukob.com\/web\/1-124\/","og_site_name":"Digital Learning Classroom","article_published_time":"2020-03-03T05:32:00+00:00","article_modified_time":"2020-03-03T06:03:15+00:00","og_image":[{"width":1320,"height":741,"url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00153.jpg?fit=1320%2C741&ssl=1","type":"image\/jpeg"}],"author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","twitter_card":"summary_large_image","twitter_creator":"@musicmankob","twitter_site":"@musicmankob","twitter_misc":{"Written by":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/krukob.com\/web\/1-124\/#article","isPartOf":{"@id":"https:\/\/krukob.com\/web\/1-124\/"},"author":{"name":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"headline":"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19","datePublished":"2020-03-03T05:32:00+00:00","dateModified":"2020-03-03T06:03:15+00:00","mainEntityOfPage":{"@id":"https:\/\/krukob.com\/web\/1-124\/"},"wordCount":397,"publisher":{"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"image":{"@id":"https:\/\/krukob.com\/web\/1-124\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00153.jpg?fit=1320%2C741&ssl=1","keywords":["\u0e2721","\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30","\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19"],"articleSection":["\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23","\u0e27\u0e34\u0e17\u0e22\u0e30\u0e10\u0e32\u0e19\u0e30"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/krukob.com\/web\/1-124\/","url":"https:\/\/krukob.com\/web\/1-124\/","name":"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 &#187;","isPartOf":{"@id":"https:\/\/krukob.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/krukob.com\/web\/1-124\/#primaryimage"},"image":{"@id":"https:\/\/krukob.com\/web\/1-124\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00153.jpg?fit=1320%2C741&ssl=1","datePublished":"2020-03-03T05:32:00+00:00","dateModified":"2020-03-03T06:03:15+00:00","breadcrumb":{"@id":"https:\/\/krukob.com\/web\/1-124\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/krukob.com\/web\/1-124\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/krukob.com\/web\/1-124\/#primaryimage","url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00153.jpg?fit=1320%2C741&ssl=1","contentUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00153.jpg?fit=1320%2C741&ssl=1","width":1320,"height":741},{"@type":"BreadcrumbList","@id":"https:\/\/krukob.com\/web\/1-124\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/krukob.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/krukob.com\/web\/#website","url":"https:\/\/krukob.com\/web\/","name":"Digital Learning Classroom","description":"Digital Learning Classroom","publisher":{"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/krukob.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6","name":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","url":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","contentUrl":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","width":500,"height":500,"caption":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14"},"logo":{"@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00153.jpg?fit=1320%2C741&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8LKk5-QT","jetpack-related-posts":[{"id":1554,"url":"https:\/\/krukob.com\/web\/1-61\/","url_meta":{"origin":3279,"position":0},"title":"\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 (\u0e23\u0e32\u0e22\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32)","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"July 12, 2018","format":false,"excerpt":"\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 (\u0e23\u0e32\u0e22\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32) \u0e27\u0e10.2 \u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e35\u0e48 \u0e28\u0e18 0206.3\/ 0635 \u0e08\u0e32\u0e01\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e01.\u0e04.\u0e28.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e25\u0e31\u0e14\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e25\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2560 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e41\u0e08\u0e49\u0e07\u0e16\u0e36\u0e07 \u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01.\u0e04.\u0e28. \u0e17\u0e35\u0e48 \u0e28\u0e18 0206.3\/\u0e27 21 \u0e25\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 5 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2560 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22 \u0e04\u0e37\u0e2d 1) \u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u00a02) \u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e30 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e15\u0e32\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 (\u0e28\u0e18 0206.3\/\u0e27 21) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e01.\u0e04.\u0e28.) \u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u2026","rel":"","context":"In &quot;\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b&quot;","block_context":{"text":"\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b","link":"https:\/\/krukob.com\/web\/category\/knowledge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/07\/009.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/07\/009.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/07\/009.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/07\/009.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2104,"url":"https:\/\/krukob.com\/web\/1-78\/","url_meta":{"origin":3279,"position":1},"title":"\u0e2a\u0e23\u0e38\u0e1b\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 (Logbook)","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"January 30, 2019","format":false,"excerpt":"\u0e2a\u0e23\u0e38\u0e1b\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e15\u0e32\u0e21 \u0e2721 \u0e02\u0e2d\u0e07 \u0e2a\u0e1e\u0e10. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 \u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e22\u0e31\u0e07\u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 \u0e01.\u0e04.\u0e28. \u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e15\u0e32\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 1 \u0e08\u0e36\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e23\u0e32\u0e1a\u0e41\u0e25\u0e30\u0e16\u0e37\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e48\u0e2d\u0e44\u0e1b","rel":"","context":"In &quot;\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b&quot;","block_context":{"text":"\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b","link":"https:\/\/krukob.com\/web\/category\/knowledge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2019\/01\/0033.jpg?fit=720%2C405&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2019\/01\/0033.jpg?fit=720%2C405&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2019\/01\/0033.jpg?fit=720%2C405&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2019\/01\/0033.jpg?fit=720%2C405&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":9043,"url":"https:\/\/krukob.com\/web\/pa\/","url_meta":{"origin":3279,"position":2},"title":"\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u200b \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 (\u0e279\/2564)","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"January 23, 2022","format":false,"excerpt":"\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u200b \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 (\u0e279\/2564)","rel":"","context":"In &quot;PA&quot;","block_context":{"text":"PA","link":"https:\/\/krukob.com\/web\/category\/academicstanding\/pa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/01\/%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%95%E0%B8%81%E0%B8%A5%E0%B8%87%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B1%E0%B8%92%E0%B8%99%E0%B8%B2%E0%B8%87%E0%B8%B2%E0%B8%99-PA.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/01\/%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%95%E0%B8%81%E0%B8%A5%E0%B8%87%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B1%E0%B8%92%E0%B8%99%E0%B8%B2%E0%B8%87%E0%B8%B2%E0%B8%99-PA.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/01\/%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%95%E0%B8%81%E0%B8%A5%E0%B8%87%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B1%E0%B8%92%E0%B8%99%E0%B8%B2%E0%B8%87%E0%B8%B2%E0%B8%99-PA.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/01\/%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%95%E0%B8%81%E0%B8%A5%E0%B8%87%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B1%E0%B8%92%E0%B8%99%E0%B8%B2%E0%B8%87%E0%B8%B2%E0%B8%99-PA.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/01\/%E0%B8%82%E0%B9%89%E0%B8%AD%E0%B8%95%E0%B8%81%E0%B8%A5%E0%B8%87%E0%B9%83%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B8%9E%E0%B8%B1%E0%B8%92%E0%B8%99%E0%B8%B2%E0%B8%87%E0%B8%B2%E0%B8%99-PA.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1471,"url":"https:\/\/krukob.com\/web\/1-55\/","url_meta":{"origin":3279,"position":3},"title":"\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"May 27, 2018","format":false,"excerpt":"\u0e15\u0e32\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e16\u0e36\u0e07 (\u0e28\u0e18 0206.3\/\u0e27 21) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e01.\u0e04.\u0e28.) \u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e04\u0e23\u0e39 \u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 (\u0e01.\u0e04.\u0e28. \u0e17\u0e35\u0e48 \u0e28\u0e18 0206.3\/0635) \u00a0 \u00a0\u0e0b\u0e36\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e04\u0e23\u0e39\u0e0a\u0e4d\u0e32\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e04\u0e23\u0e39\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29\u00a0\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e35\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 800 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e2a\u0e48\u0e27\u0e19\u00a0\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e04\u0e23\u0e39\u0e40\u0e02\u0e35\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e04\u0e23\u0e39\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1e\u0e34\u0e40\u0e28\u0e29\u00a0\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e35\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 900 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e42\u0e14\u0e22\u00a0\u0e43\u0e19\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e (PLC) \u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e35\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 50 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e2a\u0e2d\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e48\u0e33\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48 \u0e01.\u0e04.\u0e28. \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e14\u0e49\u0e27\u0e22 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e39\u0e49\u0e02\u0e2d\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e17\u0e38\u0e01\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e42\u0e14\u0e22\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01 1. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 (8 \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14) 2. \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e31\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19 (3 \u0e15\u0e31\u0e27\u0e0a\u0e35\u0e49\u0e27\u0e31\u0e14)\u2026","rel":"","context":"In &quot;\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b&quot;","block_context":{"text":"\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b","link":"https:\/\/krukob.com\/web\/category\/knowledge\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/05\/004.jpg?fit=960%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/05\/004.jpg?fit=960%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/05\/004.jpg?fit=960%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2018\/05\/004.jpg?fit=960%2C720&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3391,"url":"https:\/\/krukob.com\/web\/1-128\/","url_meta":{"origin":3279,"position":4},"title":"\u0e27 2\/2563 \u0e41\u0e19\u0e27\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30 \u0e01\u0e23\u0e13\u0e35\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"March 10, 2020","format":false,"excerpt":"\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48 \u0e01.\u0e04.\u0e28. \u0e44\u0e14\u0e49\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e48\u0e2d\u0e19\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e20\u0e32\u0e22\u0e43\u0e19 3 \u0e1b\u0e35 \u0e19\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e2b\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e23\u0e32\u0e1a\u0e41\u0e25\u0e30\u0e16\u0e37\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e19\u0e31\u0e49\u0e19","rel":"","context":"In &quot;\u0e27\u0e34\u0e17\u0e22\u0e30\u0e10\u0e32\u0e19\u0e30&quot;","block_context":{"text":"\u0e27\u0e34\u0e17\u0e22\u0e30\u0e10\u0e32\u0e19\u0e30","link":"https:\/\/krukob.com\/web\/category\/academicstanding\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00157.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00157.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00157.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00157.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/03\/00157.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4489,"url":"https:\/\/krukob.com\/web\/v21-6\/","url_meta":{"origin":3279,"position":5},"title":"\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e21\u0e35\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e21\u0e48","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"November 3, 2020","format":false,"excerpt":"\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e48\u0e32\u0e07\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e21\u0e35\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e17\u0e22\u0e10\u0e32\u0e19\u0e30\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e04\u0e23\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e21\u0e48","rel":"","context":"In &quot;\u0e27\u0e34\u0e17\u0e22\u0e30\u0e10\u0e32\u0e19\u0e30&quot;","block_context":{"text":"\u0e27\u0e34\u0e17\u0e22\u0e30\u0e10\u0e32\u0e19\u0e30","link":"https:\/\/krukob.com\/web\/category\/academicstanding\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/014d68b8-1471-444b-9095-f94138789317-1.png?fit=1200%2C578&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/014d68b8-1471-444b-9095-f94138789317-1.png?fit=1200%2C578&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/014d68b8-1471-444b-9095-f94138789317-1.png?fit=1200%2C578&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/014d68b8-1471-444b-9095-f94138789317-1.png?fit=1200%2C578&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/014d68b8-1471-444b-9095-f94138789317-1.png?fit=1200%2C578&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/3279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/comments?post=3279"}],"version-history":[{"count":15,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/3279\/revisions"}],"predecessor-version":[{"id":3302,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/3279\/revisions\/3302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media\/3299"}],"wp:attachment":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media?parent=3279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/categories?post=3279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/tags?post=3279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}