{"id":4481,"date":"2020-11-02T22:35:09","date_gmt":"2020-11-02T15:35:09","guid":{"rendered":"http:\/\/krukob.com\/web\/?p=4481"},"modified":"2020-11-02T22:35:24","modified_gmt":"2020-11-02T15:35:24","slug":"camtasia-3","status":"publish","type":"post","link":"https:\/\/krukob.com\/web\/camtasia-3\/","title":{"rendered":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9"},"content":{"rendered":"<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>\n<h2 class=\"wp-block-heading\">\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u00a0PowerPoint Presentation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21&nbsp;Microsoft PowerPoint&nbsp;\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e17\u0e33\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. \u0e40\u0e1b\u0e34\u0e14\u0e44\u0e1f\u0e25\u0e4c&nbsp;Microsoft PowerPoint&nbsp;\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. \u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e40\u0e21\u0e19\u0e39\u00a0Add-Ins\u00a0\u0e08\u0e30\u0e1b\u0e23\u0e32\u0e01\u0e01\u0e0e\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u00a0Recording Toolbar<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"216\" data-attachment-id=\"4482\" data-permalink=\"https:\/\/krukob.com\/web\/camtasia-3\/image-10-8\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-10.png?fit=474%2C216&amp;ssl=1\" data-orig-size=\"474,216\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-10\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-10.png?fit=474%2C216&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-10.png?resize=474%2C216\" alt=\"\" class=\"wp-image-4482\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-10.png?w=474&amp;ssl=1 474w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-10.png?resize=300%2C137&amp;ssl=1 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. \u0e40\u0e1b\u0e34\u0e14\u0e44\u0e1f\u0e25\u0e4c&nbsp;Microsoft PowerPoint&nbsp;\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. \u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e40\u0e21\u0e19\u0e39&nbsp;Add-Ins&nbsp;\u0e08\u0e30\u0e1b\u0e23\u0e32\u0e01\u0e01\u0e0e\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d&nbsp;Recording Toolbar<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"252\" height=\"166\" data-attachment-id=\"4483\" data-permalink=\"https:\/\/krukob.com\/web\/camtasia-3\/image-11-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-11.png?fit=252%2C166&amp;ssl=1\" data-orig-size=\"252,166\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-11\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-11.png?fit=252%2C166&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-11.png?resize=252%2C166\" alt=\"\" class=\"wp-image-4483\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. \u0e04\u0e25\u0e34\u0e01\u0e1b\u0e38\u0e48\u0e21&nbsp;<img loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"16\" src=\"blob:http:\/\/krukob.com\/070f80b0-b9a0-4de0-a25b-c5318fea92c3\">&nbsp;\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. \u0e08\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07&nbsp;Camtasia Studio Recording Paused&nbsp;\u0e04\u0e25\u0e34\u0e01\u0e1b\u0e38\u0e48\u0e21&nbsp;\u201cClick to begin recording\u201d<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"308\" height=\"132\" data-attachment-id=\"4484\" data-permalink=\"https:\/\/krukob.com\/web\/camtasia-3\/image-12-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-12.png?fit=308%2C132&amp;ssl=1\" data-orig-size=\"308,132\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-12\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-12.png?fit=308%2C132&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-12.png?resize=308%2C132\" alt=\"\" class=\"wp-image-4484\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-12.png?w=308&amp;ssl=1 308w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-12.png?resize=300%2C129&amp;ssl=1 300w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e22\u0e38\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e43\u0e2b\u0e49\u0e2b\u0e14&nbsp;CTRL+Shift+F10 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e38\u0e48\u0e21&nbsp;Esc&nbsp;\u0e1a\u0e19\u0e41\u0e1b\u0e49\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6. \u0e08\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e16\u0e32\u0e21\u0e27\u0e48\u0e32\u0e08\u0e30\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e15\u0e48\u0e2d (Continue recording)&nbsp;\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e2b\u0e22\u0e38\u0e14 (Stop Recording)<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"312\" height=\"236\" data-attachment-id=\"4485\" data-permalink=\"https:\/\/krukob.com\/web\/camtasia-3\/image-13-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-13.png?fit=312%2C236&amp;ssl=1\" data-orig-size=\"312,236\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image-13\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-13.png?fit=312%2C236&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-13.png?resize=312%2C236\" alt=\"\" class=\"wp-image-4485\" srcset=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-13.png?w=312&amp;ssl=1 312w, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/image-13.png?resize=300%2C227&amp;ssl=1 300w\" sizes=\"auto, (max-width: 312px) 100vw, 312px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7. \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e25\u0e34\u0e01\u0e1b\u0e38\u0e48\u0e21\u00a0\u201cStop Recording\u201d\u00a0\u0e08\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e44\u0e1f\u0e25\u0e4c \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e1f\u0e25\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e44\u0e1f\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e14\u0e1b\u0e38\u0e48\u0e21\u00a0save<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">8. \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e01\u0e32\u0e23\u00a0save\u00a0\u0e44\u0e1f\u0e25\u0e4c\u0e41\u0e25\u0e49\u0e27 \u0e08\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e07\u0e32\u0e19\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e14 \u0e2b\u0e32\u0e01\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e21\u0e19\u0e39\u00a0Produce your recording\u00a0\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e19\u0e32\u0e21\u0e2a\u0e01\u0e38\u0e25\u0e44\u0e1f\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e21\u0e19\u0e39\u00a0Edit your recording\u00a0\u0e08\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e44\u0e1f\u0e25\u0e4c\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e44\u0e14\u0e49<\/p>\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<script>\r\n  (adsbygoogle = window.adsbygoogle || []).push({\r\n    google_ad_client: \"ca-pub-2163185472750267\",\r\n    enable_page_level_ads: true\r\n  });\r\n<\/script>","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Microsoft PowerPoint \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19<\/p>\n","protected":false},"author":1,"featured_media":4486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[216,1],"tags":[],"class_list":["post-4481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camtasia","category-knowledge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9 &#187;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/krukob.com\/web\/camtasia-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9 &#187;\" \/>\n<meta property=\"og:description\" content=\"\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Microsoft PowerPoint \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/krukob.com\/web\/camtasia-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Learning Classroom\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T15:35:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-02T15:35:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00224.jpg?fit=1320%2C741&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1320\" \/>\n\t<meta property=\"og:image:height\" content=\"741\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@musicmankob\" \/>\n<meta name=\"twitter:site\" content=\"@musicmankob\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/\"},\"author\":{\"name\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"headline\":\"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9\",\"datePublished\":\"2020-11-02T15:35:09+00:00\",\"dateModified\":\"2020-11-02T15:35:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/\"},\"wordCount\":62,\"publisher\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"image\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/00224.jpg?fit=1320%2C741&ssl=1\",\"articleSection\":[\"Camtasia\",\"\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/\",\"name\":\"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9 &#187;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/00224.jpg?fit=1320%2C741&ssl=1\",\"datePublished\":\"2020-11-02T15:35:09+00:00\",\"dateModified\":\"2020-11-02T15:35:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/00224.jpg?fit=1320%2C741&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/00224.jpg?fit=1320%2C741&ssl=1\",\"width\":1320,\"height\":741},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/camtasia-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/krukob.com\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/krukob.com\\\/web\\\/\",\"name\":\"Digital Learning Classroom\",\"description\":\"Digital Learning Classroom\",\"publisher\":{\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/krukob.com\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/krukob.com\\\/web\\\/#\\\/schema\\\/person\\\/920adef1e1740804d6bc536a19fc4ec6\",\"name\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"url\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"contentUrl\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\",\"width\":500,\"height\":500,\"caption\":\"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14\"},\"logo\":{\"@id\":\"https:\\\/\\\/i2.wp.com\\\/krukob.com\\\/web\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9 &#187;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/krukob.com\/web\/camtasia-3\/","og_locale":"en_US","og_type":"article","og_title":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9 &#187;","og_description":"\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Microsoft PowerPoint \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19","og_url":"https:\/\/krukob.com\/web\/camtasia-3\/","og_site_name":"Digital Learning Classroom","article_published_time":"2020-11-02T15:35:09+00:00","article_modified_time":"2020-11-02T15:35:24+00:00","og_image":[{"width":1320,"height":741,"url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00224.jpg?fit=1320%2C741&ssl=1","type":"image\/jpeg"}],"author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","twitter_card":"summary_large_image","twitter_creator":"@musicmankob","twitter_site":"@musicmankob","twitter_misc":{"Written by":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/krukob.com\/web\/camtasia-3\/#article","isPartOf":{"@id":"https:\/\/krukob.com\/web\/camtasia-3\/"},"author":{"name":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"headline":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9","datePublished":"2020-11-02T15:35:09+00:00","dateModified":"2020-11-02T15:35:24+00:00","mainEntityOfPage":{"@id":"https:\/\/krukob.com\/web\/camtasia-3\/"},"wordCount":62,"publisher":{"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"image":{"@id":"https:\/\/krukob.com\/web\/camtasia-3\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00224.jpg?fit=1320%2C741&ssl=1","articleSection":["Camtasia","\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/krukob.com\/web\/camtasia-3\/","url":"https:\/\/krukob.com\/web\/camtasia-3\/","name":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9 &#187;","isPartOf":{"@id":"https:\/\/krukob.com\/web\/#website"},"primaryImageOfPage":{"@id":"https:\/\/krukob.com\/web\/camtasia-3\/#primaryimage"},"image":{"@id":"https:\/\/krukob.com\/web\/camtasia-3\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00224.jpg?fit=1320%2C741&ssl=1","datePublished":"2020-11-02T15:35:09+00:00","dateModified":"2020-11-02T15:35:24+00:00","breadcrumb":{"@id":"https:\/\/krukob.com\/web\/camtasia-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/krukob.com\/web\/camtasia-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/krukob.com\/web\/camtasia-3\/#primaryimage","url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00224.jpg?fit=1320%2C741&ssl=1","contentUrl":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00224.jpg?fit=1320%2C741&ssl=1","width":1320,"height":741},{"@type":"BreadcrumbList","@id":"https:\/\/krukob.com\/web\/camtasia-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/krukob.com\/web\/"},{"@type":"ListItem","position":2,"name":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d PowerPoint Presentation \u0e08\u0e32\u0e01\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9"}]},{"@type":"WebSite","@id":"https:\/\/krukob.com\/web\/#website","url":"https:\/\/krukob.com\/web\/","name":"Digital Learning Classroom","description":"Digital Learning Classroom","publisher":{"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/krukob.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/krukob.com\/web\/#\/schema\/person\/920adef1e1740804d6bc536a19fc4ec6","name":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","url":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","contentUrl":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500","width":500,"height":500,"caption":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14"},"logo":{"@id":"https:\/\/i2.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/141723375_10214243495481420_8857316148753634287_n-removebg-preview.png?fit=500%2C500"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00224.jpg?fit=1320%2C741&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p8LKk5-1ah","jetpack-related-posts":[{"id":4469,"url":"https:\/\/krukob.com\/web\/camtasia-2\/","url_meta":{"origin":4481,"position":0},"title":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d (Capture) \u0e14\u0e49\u0e27\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"November 2, 2020","format":false,"excerpt":"\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d (Capture) \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e19","rel":"","context":"In &quot;Camtasia&quot;","block_context":{"text":"Camtasia","link":"https:\/\/krukob.com\/web\/category\/instruction_media\/camtasia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00223.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00223.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00223.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00223.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00223.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4459,"url":"https:\/\/krukob.com\/web\/camtasia\/","url_meta":{"origin":4481,"position":1},"title":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 1 \u0e40\u0e21\u0e19\u0e39\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e02\u0e2d\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"November 2, 2020","format":false,"excerpt":"\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Camtasia Studio 9 \u0e40\u0e1b\u0e47\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e08\u0e31\u0e1a\u0e20\u0e32\u0e1e\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d (Capture) \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d \u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e40\u0e1e\u0e25\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e04\u0e19\u0e16\u0e48\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e01\u0e47\u0e44\u0e14\u0e49","rel":"","context":"In &quot;Camtasia&quot;","block_context":{"text":"Camtasia","link":"https:\/\/krukob.com\/web\/category\/instruction_media\/camtasia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00222.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00222.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00222.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00222.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00222.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6391,"url":"https:\/\/krukob.com\/web\/obs\/","url_meta":{"origin":4481,"position":2},"title":"\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 OBS","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"April 1, 2021","format":false,"excerpt":"\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 OBS","rel":"","context":"In &quot;\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19&quot;","block_context":{"text":"\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19","link":"https:\/\/krukob.com\/web\/category\/instruction_media\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002814.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002814.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002814.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002814.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002814.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4823,"url":"https:\/\/krukob.com\/web\/loom-4\/","url_meta":{"origin":4481,"position":3},"title":"\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 4 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Loom \u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"November 18, 2020","format":false,"excerpt":"\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 Loom \u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c","rel":"","context":"In &quot;Loom&quot;","block_context":{"text":"Loom","link":"https:\/\/krukob.com\/web\/category\/instruction_media\/loom\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00241.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00241.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00241.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00241.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2020\/11\/00241.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6465,"url":"https:\/\/krukob.com\/web\/obs-7\/","url_meta":{"origin":4481,"position":4},"title":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49 OBS \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 : \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 7 \u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01 Scenes","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"April 7, 2021","format":false,"excerpt":"\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49 OBS \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 : \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 7 \u0e01\u0e32\u0e23\u0e41\u0e17\u0e23\u0e01 Scenes","rel":"","context":"In &quot;OBS&quot;","block_context":{"text":"OBS","link":"https:\/\/krukob.com\/web\/category\/instruction_media\/obs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002822.jpg?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002822.jpg?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002822.jpg?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002822.jpg?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2021\/04\/002822.jpg?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9339,"url":"https:\/\/krukob.com\/web\/cloud\/","url_meta":{"origin":4481,"position":5},"title":"\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 CloudReady","author":"\u0e14\u0e23.\u0e2d\u0e19\u0e38\u0e28\u0e23 \u0e2b\u0e07\u0e29\u0e4c\u0e02\u0e38\u0e19\u0e17\u0e14","date":"February 16, 2022","format":false,"excerpt":"\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 CloudReady","rel":"","context":"In &quot;CloudReady&quot;","block_context":{"text":"CloudReady","link":"https:\/\/krukob.com\/web\/category\/instruction_media\/cloudready\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/02\/CloudReady-2.png?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/02\/CloudReady-2.png?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/02\/CloudReady-2.png?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/02\/CloudReady-2.png?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/krukob.com\/web\/wp-content\/uploads\/2022\/02\/CloudReady-2.png?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/4481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/comments?post=4481"}],"version-history":[{"count":1,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/4481\/revisions"}],"predecessor-version":[{"id":4487,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/posts\/4481\/revisions\/4487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media\/4486"}],"wp:attachment":[{"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/media?parent=4481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/categories?post=4481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/krukob.com\/web\/wp-json\/wp\/v2\/tags?post=4481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}